{"id":18241,"date":"2020-05-13T20:28:31","date_gmt":"2020-05-14T01:28:31","guid":{"rendered":"https:\/\/patternenergy.com\/une-falaise-des-serpents-et-des-cactus\/"},"modified":"2026-03-11T20:20:45","modified_gmt":"2026-03-12T01:20:45","slug":"une-falaise-des-serpents-et-des-cactus","status":"publish","type":"post","link":"https:\/\/patternenergy.com\/fr\/une-falaise-des-serpents-et-des-cactus\/","title":{"rendered":"Une falaise, des serpents et des cactus !"},"content":{"rendered":"<p>Bonjour Nouveau Mexique, c&rsquo;est moi, votre humble correspondant, Ed Domain, Nouveau au Nouveau Mexique. Poursuivez votre lecture et assistez \u00e0 ma derni\u00e8re aventure.<\/p>\n<p>Je suis rest\u00e9e \u00e0 la maison, essayant de me prot\u00e9ger comme beaucoup d&rsquo;entre vous. Certaines de mes exp\u00e9riences dans notre nouvelle r\u00e9alit\u00e9 ont \u00e9t\u00e9 amusantes : <a href=\"https:\/\/patternenergy.com\/fr\/un-chat-nomme-covid\/\">Je me suis li\u00e9 d&rsquo;amiti\u00e9 avec un chat.<\/a> Je pr\u00e9pare le petit-d\u00e9jeuner tous les matins et j&rsquo;aime cette activit\u00e9. Ma vie est un peu plus lente, mais j&rsquo;appr\u00e9cie les choses d&rsquo;une nouvelle mani\u00e8re.<\/p>\n<p>Je suis une adepte de la randonn\u00e9e, et pour faire un peu d&rsquo;exercice et me d\u00e9barrasser du \u00ab\u00a0blues de la maison\u00a0\u00bb, j&rsquo;ai cherch\u00e9 des sentiers pr\u00e8s d&rsquo;Albuquerque sur une application que j&rsquo;aime bien, \u00ab\u00a0All Trails\u00a0\u00bb, et j&rsquo;ai vu ces options :<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6402\" src=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/Trail-list-near-me-473x1024-1.jpg\" alt=\"\" width=\"473\" height=\"1024\" srcset=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/Trail-list-near-me-473x1024-1.jpg 473w, https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/Trail-list-near-me-473x1024-1-139x300.jpg 139w\" sizes=\"auto, (max-width: 473px) 100vw, 473px\" \/><\/p>\n<p>Les plus perspicaces d&rsquo;entre vous verront que j&rsquo;ai choisi \u00ab\u00a0Eye Of The Sandias Loop Trail\u00a0\u00bb et qu&rsquo;il est indiqu\u00e9 \u00ab\u00a0HARD\u00a0\u00bb (difficile) alors que les autres choix pr\u00e8s de moi \u00e9taient indiqu\u00e9s \u00ab\u00a0EASY\u00a0\u00bb (facile).<\/p>\n<p>Lorsqu&rsquo;on me donne le choix entre la difficult\u00e9 et la facilit\u00e9, je choisis la difficult\u00e9 dans 99 % des cas. Je me suis dit : \u00ab\u00a0J&rsquo;ai besoin d&rsquo;une piste difficile aujourd&rsquo;hui, et en plus, ce n&rsquo;est qu&rsquo;\u00e0 20 minutes de route de chez moi. A quel point cela peut-il \u00eatre difficile ? Un peu moins de 5 miles ? Je vais m&rsquo;en sortir et faire une bonne s\u00e9ance d&rsquo;entra\u00eenement, c&rsquo;est facile. Allons-y\u00a0\u00bb<\/p>\n<p>J&rsquo;\u00e9tais si na\u00efve au Nouveau-Mexique, si na\u00efve.<\/p>\n<div id=\"attachment_6403\" style=\"width: 1210px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-6403\" class=\"size-full wp-image-6403\" src=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/hike-up-hill.jpg\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/hike-up-hill.jpg 1200w, https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/hike-up-hill-300x200.jpg 300w, https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/hike-up-hill-1024x683.jpg 1024w, https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/hike-up-hill-768x512.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><p id=\"caption-attachment-6403\" class=\"wp-caption-text\"><strong>Toujours plus haut<\/strong><\/p><\/div>\n<p>J&rsquo;ai gar\u00e9 ma Jeep et je me suis mis en route. Au bout d&rsquo;un kilom\u00e8tre, j&rsquo;ai commenc\u00e9 \u00e0 le sentir dans mes muscles et j&rsquo;ai jou\u00e9 un jeu avec moi-m\u00eame &#8211; oui, le sentier \u00e9tait difficile, mais par exp\u00e9rience, je savais que c&rsquo;\u00e9tait surtout mental et que je pouvais continuer \u00e0 pousser. Je choisissais un objet au loin et me disais : \u00ab\u00a0Je ferai une pause lorsque j&rsquo;atteindrai cet arbre tordu, ce rocher, ce virage dans le sentier, etc. J&rsquo;atteignais ce point de rep\u00e8re, puis le d\u00e9passais et en choisissais un autre.<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6404\" src=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/hike-up-hill-2.jpg\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/hike-up-hill-2.jpg 1200w, https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/hike-up-hill-2-300x200.jpg 300w, https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/hike-up-hill-2-1024x683.jpg 1024w, https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/hike-up-hill-2-768x512.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>En avan\u00e7ant, le sentier se termine souvent en cul-de-sac et je me heurte \u00e0 d&rsquo;\u00e9normes rochers. J&rsquo;\u00e9tais confus. J&rsquo;ai v\u00e9rifi\u00e9 la carte, et oui, j&rsquo;\u00e9tais bien sur le sentier &#8211; pour continuer, je devais enjamber les rochers qui se trouvaient devant moi. Je devais avoir confiance en ma force et en ma capacit\u00e9 \u00e0 me hisser sur des rochers plus grands que moi et \u00e0 faire une chute contr\u00f4l\u00e9e de l&rsquo;autre c\u00f4t\u00e9, en veillant \u00e0 ne pas me tordre la cheville ou \u00e0 faire quelque chose de stupide comme enfoncer ma main dans un cactus.<\/p>\n<p>Ensuite, j&rsquo;ai fait quelque chose de stupide et j&rsquo;ai mis ma main dans un cactus.<\/p>\n<p>J&rsquo;\u00e9tais fier de la force avec laquelle je poussais tout en g\u00e9rant les rochers de plus en plus gros que je devais franchir, et j&rsquo;ai essay\u00e9 d&rsquo;acc\u00e9l\u00e9rer. J&rsquo;ai atteint le sommet d&rsquo;un autre gros tas de pierres, j&rsquo;ai saut\u00e9 un peu trop confiant, j&rsquo;ai tr\u00e9buch\u00e9 en arrivant sur le sentier, je suis tomb\u00e9 en avant \u00e0 cause de l&rsquo;angle d&rsquo;ascension et je me suis rattrap\u00e9 sur mes mains &#8211; ma main gauche en tout cas. Ma main droite s&rsquo;est heurt\u00e9e \u00e0 un cactus et j&rsquo;ai senti ma main transperc\u00e9e par ce qui ressemblait \u00e0 9 millions d&rsquo;aiguilles \u00e0 tricoter.<\/p>\n<p>C&rsquo;est une longue histoire, mais la douleur ne m&rsquo;est pas \u00e9trang\u00e8re. Je me suis fig\u00e9e sur place, j&rsquo;ai ferm\u00e9 les yeux et je me suis dit : \u00ab\u00a0NE PANIQUEZ PAS\u00a0\u00bb. Ma main me piquait, mais je ne voulais pas aggraver la situation. Je savais que \u00e7a allait \u00eatre moche.<\/p>\n<div id=\"attachment_6405\" style=\"width: 1210px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-6405\" class=\"size-full wp-image-6405\" src=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/pride-rock.jpg\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/pride-rock.jpg 1200w, https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/pride-rock-300x200.jpg 300w, https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/pride-rock-1024x683.jpg 1024w, https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/pride-rock-768x512.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><p id=\"caption-attachment-6405\" class=\"wp-caption-text\"><strong>La magie du sentier<\/strong><\/p><\/div>\n<p>Apr\u00e8s avoir pris mes aises, j&rsquo;ai ouvert les yeux et j&rsquo;ai ri nerveusement de ma situation. Ma main \u00e9tait en plein milieu du cactus. Je me suis d\u00e9gag\u00e9e, j&rsquo;ai regard\u00e9 ma paume et j&rsquo;ai vu les 9 millions d&rsquo;aiguilles \u00e0 tricoter qui sortaient de ma main. Certains \u00e9taient longs et blancs, d&rsquo;autres \u00e9taient courts et d&rsquo;un rouge dor\u00e9. Tr\u00e8s jolies, si elles n&rsquo;\u00e9taient pas coinc\u00e9es dans ma main. Je me suis retourn\u00e9 vers le cactus, qui n&rsquo;\u00e9tait pas plus mal en point pour l&rsquo;exp\u00e9rience. Je suis presque s\u00fbr qu&rsquo;il s&rsquo;est moqu\u00e9 de moi.<\/p>\n<p>J&rsquo;en \u00e9tais \u00e0 trois kilom\u00e8tres. Je ne pouvais pas rentrer chez moi, je d\u00e9teste abandonner de toute fa\u00e7on, et parce que je suis l&rsquo;une des personnes les plus t\u00eatues qui soient, j&rsquo;allais terminer ce parcours. J&rsquo;ai trouv\u00e9 un rocher, je me suis assis et j&rsquo;ai commenc\u00e9 \u00e0 tirer sur les aiguilles. L&rsquo;exp\u00e9rience s&rsquo;est d\u00e9roul\u00e9e comme suit :<\/p>\n<p>*TIRER* \u00ab\u00a0Ow\u00a0\u00bb<\/p>\n<p>*TIRER* \u00ab\u00a0Ow\u00a0\u00bb<\/p>\n<p>*TIRER* \u00ab\u00a0Ow\u00a0\u00bb<\/p>\n<p>Cela a dur\u00e9 40 minutes, et pendant tout ce temps, je n&rsquo;ai jamais vu personne d&rsquo;autre. (Je n&rsquo;ai vu personne d&rsquo;autre de toute la randonn\u00e9e jusqu&rsquo;\u00e0 ce que je sois beaucoup plus bas, vers la fin). Ma main saignait et ma paume ressemblait \u00e0 un d\u00e9sastre. Je me suis remis \u00e0 rire. J&rsquo;ai fini par retirer tout ce que je pouvais, ma main me lan\u00e7ait et j&rsquo;avais l&rsquo;impression qu&rsquo;il y avait des dizaines de petits morceaux que je n&rsquo;arriverais jamais \u00e0 retirer ici, sur la montagne.<\/p>\n<p>J&rsquo;ai regard\u00e9 la carte. Je n&rsquo;en \u00e9tais pas encore \u00e0 la moiti\u00e9. Plut\u00f4t que d&rsquo;\u00eatre constern\u00e9, cela m&rsquo;a rendu r\u00e9solu. J&rsquo;ai aboy\u00e9 un grand \u00ab\u00a0HOOAH\u00a0\u00bb militaire et j&rsquo;ai commenc\u00e9 \u00e0 avancer.<\/p>\n<p>Alors que je me rapprochais du sommet, du coin de l&rsquo;\u0153il, j&rsquo;ai vu un gigantesque serpent se faufiler \u00e0 l&rsquo;ext\u00e9rieur. J&rsquo;ai recul\u00e9 d&rsquo;un bond, j&rsquo;ai fait un bruit comme \u00ab\u00a0Whaaa whoah, hey l\u00e0\u00a0\u00bb et je me suis fig\u00e9. Le serpent s&rsquo;est fig\u00e9 lui aussi &#8211; et j&rsquo;ai recommenc\u00e9 \u00e0 rire. Le serpent n&rsquo;\u00e9tait PAS gigantesque et il n&rsquo;y avait pas de quoi avoir peur. J&rsquo;ai donn\u00e9 un petit coup de pied dans la terre, et il a fait demi-tour et est reparti comme il \u00e9tait venu.<\/p>\n<div id=\"attachment_6406\" style=\"width: 1210px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-6406\" class=\"size-full wp-image-6406\" src=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/lions-den.jpg\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/lions-den.jpg 1200w, https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/lions-den-300x200.jpg 300w, https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/lions-den-1024x683.jpg 1024w, https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/lions-den-768x512.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><p id=\"caption-attachment-6406\" class=\"wp-caption-text\"><strong>Pour une fois, une porte !<\/strong><\/p><\/div>\n<p>Toujours en riant, j&rsquo;ai continu\u00e9 \u00e0 grimper et trois minutes plus tard, j&rsquo;ai v\u00e9cu exactement la m\u00eame exp\u00e9rience. Il y a quelque chose dans un serpent qui sort de nulle part qui m&rsquo;attire, \u00e0 chaque fois. Une fois que j&rsquo;ai eu la chance de me d\u00e9tendre et de regarder de plus pr\u00e8s, je suis calme, mais les serpents ont une fa\u00e7on de me surprendre que les petits mammif\u00e8res n&rsquo;ont pas.<\/p>\n<p>J&rsquo;ai atteint le sommet, mais le sentier a disparu \u00e0 nouveau. Le vent s&rsquo;est lev\u00e9 et s&rsquo;est intensifi\u00e9 &#8211; j&rsquo;\u00e9tais semi-expos\u00e9 et j&rsquo;ai \u00e9t\u00e9 un peu secou\u00e9.<\/p>\n<p>J&rsquo;ai grimp\u00e9 sur un rocher exceptionnellement grand et j&rsquo;ai eu une vue extraordinaire &#8211; c&rsquo;\u00e9tait le sommet de la montagne. Je n&rsquo;ai pas pu aller plus haut et j&rsquo;ai eu droit \u00e0 une vue absolument magnifique d&rsquo;Albuquerque en contrebas, avec des cha\u00eenes de montagnes lointaines \u00e0 l&rsquo;ouest.<\/p>\n<p>J&rsquo;\u00e9tais \u00e9galement bloqu\u00e9. J&rsquo;ai cherch\u00e9 le sentier, et je l&rsquo;ai vu reprendre \u00e0 environ 200 pieds devant moi, j&rsquo;ai r\u00e9alis\u00e9 que j&rsquo;avais fait une erreur et que j&rsquo;avais manqu\u00e9 la partie du sentier qui faisait le tour du sommet. Bien que j&rsquo;aie pu remonter en toute s\u00e9curit\u00e9, j&rsquo;ai vu que le retour par le m\u00eame chemin m&rsquo;obligerait \u00e0 faire une chute qui ne me paraissait pas judicieuse.<\/p>\n<p>Pour avancer et revenir sur le sentier et commencer ma descente, j&rsquo;ai d\u00fb prendre un risque calcul\u00e9. Il y aurait une escalade sur le bord de la falaise, et je savais que si je faisais attention, ce ne serait pas difficile.<\/p>\n<p>Lentement, prudemment, \u00e0 quatre pattes, j&rsquo;ai ramp\u00e9 sur le rebord. C&rsquo;\u00e9tait une \u00e9norme paroi rocheuse, plus large que longue, et j&rsquo;ai vu que si je ne faisais pas attention, la descente serait extr\u00eamement longue.<\/p>\n<div id=\"attachment_6407\" style=\"width: 1210px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-6407\" class=\"size-full wp-image-6407\" src=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/view-from-the-top.jpg\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/view-from-the-top.jpg 1200w, https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/view-from-the-top-300x200.jpg 300w, https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/view-from-the-top-1024x683.jpg 1024w, https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/view-from-the-top-768x512.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><p id=\"caption-attachment-6407\" class=\"wp-caption-text\"><strong>Le \u00ab\u00a0sentier\u00a0\u00bb<\/strong><\/p><\/div>\n<p>&nbsp;<\/p>\n<p>J&rsquo;ai avanc\u00e9 de quelques m\u00e8tres, sentant les \u00e9clats de cactus \u00e0 chaque placement de main quand le vent s&rsquo;est mis \u00e0 hurler et m&rsquo;a frapp\u00e9 de plein fouet ; il m&rsquo;a fait tomber de c\u00f4t\u00e9, je me suis laiss\u00e9 tomber et je me suis mis \u00e0 plat ventre autant que possible.<\/p>\n<p>J&rsquo;ai attendu que le vent se calme, j&rsquo;ai commenc\u00e9 \u00e0 ramper et j&rsquo;ai \u00e9t\u00e9 frapp\u00e9 \u00e0 nouveau &#8211; cela m&rsquo;a suffi. Je me suis couch\u00e9 sur le dos et j&rsquo;ai commenc\u00e9 \u00e0 rire. En m&rsquo;aplatissant, le vent a hurl\u00e9 au-dessus de moi, et j&rsquo;ai su que je ne voulais pas rester ici longtemps au cas o\u00f9 les choses deviendraient plus dramatiques.<\/p>\n<p>Mon c\u0153ur battait la chamade, l&rsquo;adr\u00e9naline montait en fl\u00e8che et j&rsquo;ai pouss\u00e9 un rugissement. Je me sentais vivant d&rsquo;une mani\u00e8re qu&rsquo;il me faut g\u00e9n\u00e9ralement aller au fin fond de la nature pour ressentir, et je me trouvais \u00e0 vingt minutes de chez moi. Le rugissement termin\u00e9, je me suis remis au travail.<\/p>\n<div id=\"attachment_6408\" style=\"width: 1210px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-6408\" class=\"size-full wp-image-6408\" src=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/view-from-the-top2.jpg\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/view-from-the-top2.jpg 1200w, https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/view-from-the-top2-300x200.jpg 300w, https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/view-from-the-top2-1024x683.jpg 1024w, https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/view-from-the-top2-768x512.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><p id=\"caption-attachment-6408\" class=\"wp-caption-text\"><strong>Vue du bord<\/strong><\/p><\/div>\n<p>J&rsquo;ai pris quelques photos, je voulais me souvenir de ce moment. Je remets mon t\u00e9l\u00e9phone dans ma poche. Lentement, prudemment, le vent hurlant, je suis rest\u00e9 \u00e0 plat sur le dos et j&rsquo;ai d\u00e9plac\u00e9 mon corps sur le c\u00f4t\u00e9 tr\u00e8s, tr\u00e8s lentement, et tr\u00e8s, tr\u00e8s prudemment.<\/p>\n<p>Je suis arriv\u00e9 au bord oppos\u00e9 de la falaise, j&rsquo;ai regard\u00e9 en bas et j&rsquo;ai vu un chemin d\u00e9gag\u00e9 pour descendre &#8211; j&rsquo;ai chut\u00e9 de quelques pieds sur le rocher en dessous alors que le vent continuait \u00e0 hurler, mais j&rsquo;\u00e9tais en s\u00e9curit\u00e9 maintenant et j&rsquo;ai escalad\u00e9 quelques autres gros rochers, j&rsquo;ai pris le sentier, j&rsquo;ai saut\u00e9 sur quelques centaines de pieds, sentant chaque muscle de mon corps et me sentant VIVANT d&rsquo;une mani\u00e8re que d&rsquo;autres aventuriers hocheront la t\u00eate et comprendront.<\/p>\n<p>&nbsp;<\/p>\n<p>VID\u00c9O<\/p>\n<p>&nbsp;<\/p>\n<p>Je me suis arr\u00eat\u00e9 et j&rsquo;ai regard\u00e9 en arri\u00e8re. Je riais de ma victoire m\u00eal\u00e9e de peur, accentu\u00e9e par l&rsquo;adr\u00e9naline qui m&rsquo;envahissait comme du carburant pour fus\u00e9e, et j&rsquo;ai r\u00e9alis\u00e9 cette vid\u00e9o. Vous pouvez voir l&rsquo;expression sauvage dans mes yeux &#8211; je n&rsquo;arrivais pas \u00e0 trouver les mots, je repassais ma petite aventure dans ma t\u00eate. S&rsquo;il n&rsquo;y avait pas eu de vent, la situation n&rsquo;aurait pas \u00e9t\u00e9 aussi dramatique. (J&rsquo;ai aussi vraiment besoin d&rsquo;une coupe de cheveux).<\/p>\n<p>Il m&rsquo;a fallu plus de deux heures pour terminer le sentier, avec une pause de 40 minutes pour retirer les aiguilles de ma main.<\/p>\n<p>Avec autant d&rsquo;aventures \u00e0 seulement vingt minutes de chez nous, le Nouveau-Mexique et moi allons nous entendre \u00e0 merveille.<\/p>\n<p>J&rsquo;ai bien dormi cette nuit-l\u00e0 et j&rsquo;ai h\u00e2te de recommencer.<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6409\" src=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/Finished-503x1024-1.png\" alt=\"\" width=\"503\" height=\"1024\" srcset=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/Finished-503x1024-1.png 503w, https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/Finished-503x1024-1-147x300.png 147w\" sizes=\"auto, (max-width: 503px) 100vw, 503px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonjour Nouveau Mexique, c&rsquo;est moi, votre humble correspondant, Ed Domain, Nouveau au Nouveau Mexique. Poursuivez votre lecture et assistez \u00e0 ma derni\u00e8re aventure. Je suis rest\u00e9e \u00e0 la maison, essayant de me prot\u00e9ger comme beaucoup d&rsquo;entre vous. Certaines de mes exp\u00e9riences dans notre nouvelle r\u00e9alit\u00e9 ont \u00e9t\u00e9 amusantes : Je me suis li\u00e9 d&rsquo;amiti\u00e9 avec [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13531,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[448],"tags":[],"sub_site":[482],"class_list":["post-18241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Une falaise, des serpents et des cactus ! - Pattern Energy<\/title>\n<meta name=\"description\" content=\"Les plus perspicaces d&#039;entre vous verront que j&#039;ai choisi &quot;Eye Of The Sandias Loop Trail&quot; et qu&#039;il est indiqu\u00e9 &quot;HARD&quot; (difficile) alors que les autres choix \u00e9taient indiqu\u00e9s &quot;EASY&quot; (facile).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/patternenergy.com\/fr\/une-falaise-des-serpents-et-des-cactus\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Une falaise, des serpents et des cactus ! - Pattern Energy\" \/>\n<meta property=\"og:description\" content=\"Les plus perspicaces d&#039;entre vous verront que j&#039;ai choisi &quot;Eye Of The Sandias Loop Trail&quot; et qu&#039;il est indiqu\u00e9 &quot;HARD&quot; (difficile) alors que les autres choix \u00e9taient indiqu\u00e9s &quot;EASY&quot; (facile).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/patternenergy.com\/fr\/une-falaise-des-serpents-et-des-cactus\/\" \/>\n<meta property=\"og:site_name\" content=\"Pattern Energy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PatternEnergy\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-14T01:28:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-12T01:20:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/hike-up-hill.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ptrndmn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ptrndmn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/une-falaise-des-serpents-et-des-cactus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/une-falaise-des-serpents-et-des-cactus\\\/\"},\"author\":{\"name\":\"ptrndmn\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/#\\\/schema\\\/person\\\/33965a118f27fded0be086c056aa2706\"},\"headline\":\"Une falaise, des serpents et des cactus !\",\"datePublished\":\"2020-05-14T01:28:31+00:00\",\"dateModified\":\"2026-03-12T01:20:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/une-falaise-des-serpents-et-des-cactus\\\/\"},\"wordCount\":1924,\"publisher\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/une-falaise-des-serpents-et-des-cactus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/patternenergy.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/hike-up-hill.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/une-falaise-des-serpents-et-des-cactus\\\/\",\"url\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/une-falaise-des-serpents-et-des-cactus\\\/\",\"name\":\"Une falaise, des serpents et des cactus ! - Pattern Energy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/une-falaise-des-serpents-et-des-cactus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/une-falaise-des-serpents-et-des-cactus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/patternenergy.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/hike-up-hill.jpg\",\"datePublished\":\"2020-05-14T01:28:31+00:00\",\"dateModified\":\"2026-03-12T01:20:45+00:00\",\"description\":\"Les plus perspicaces d'entre vous verront que j'ai choisi \\\"Eye Of The Sandias Loop Trail\\\" et qu'il est indiqu\u00e9 \\\"HARD\\\" (difficile) alors que les autres choix \u00e9taient indiqu\u00e9s \\\"EASY\\\" (facile).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/une-falaise-des-serpents-et-des-cactus\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/patternenergy.com\\\/fr\\\/une-falaise-des-serpents-et-des-cactus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/une-falaise-des-serpents-et-des-cactus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/patternenergy.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/hike-up-hill.jpg\",\"contentUrl\":\"https:\\\/\\\/patternenergy.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/hike-up-hill.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Ever upwards\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/une-falaise-des-serpents-et-des-cactus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Une falaise, des serpents et des cactus !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/\",\"name\":\"Pattern Energy\",\"description\":\"Nous d\u00e9veloppons, construisons, poss\u00e9dons et exploitons des projets \u00e9oliens, solaires, de transport et de stockage d'\u00e9nergie de haute qualit\u00e9 dans le monde entier.\",\"publisher\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/#organization\",\"name\":\"Pattern Energy\",\"url\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/patternenergy.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Pattern-Energy-Media-thumbnail-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/patternenergy.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Pattern-Energy-Media-thumbnail-logo.jpg\",\"width\":1200,\"height\":627,\"caption\":\"Pattern Energy\"},\"image\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PatternEnergy\\\/\",\"https:\\\/\\\/instagram.com\\\/patternenergy?utm_medium=copy_link\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pattern-energy\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/PatternEnergy?app=desktop\",\"https:\\\/\\\/web.cauze.com\\\/company\\\/293\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/#\\\/schema\\\/person\\\/33965a118f27fded0be086c056aa2706\",\"name\":\"ptrndmn\",\"sameAs\":[\"https:\\\/\\\/patternenergy.com\"],\"url\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/author\\\/ptrndmn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Une falaise, des serpents et des cactus ! - Pattern Energy","description":"Les plus perspicaces d'entre vous verront que j'ai choisi \"Eye Of The Sandias Loop Trail\" et qu'il est indiqu\u00e9 \"HARD\" (difficile) alors que les autres choix \u00e9taient indiqu\u00e9s \"EASY\" (facile).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/patternenergy.com\/fr\/une-falaise-des-serpents-et-des-cactus\/","og_locale":"fr_FR","og_type":"article","og_title":"Une falaise, des serpents et des cactus ! - Pattern Energy","og_description":"Les plus perspicaces d'entre vous verront que j'ai choisi \"Eye Of The Sandias Loop Trail\" et qu'il est indiqu\u00e9 \"HARD\" (difficile) alors que les autres choix \u00e9taient indiqu\u00e9s \"EASY\" (facile).","og_url":"https:\/\/patternenergy.com\/fr\/une-falaise-des-serpents-et-des-cactus\/","og_site_name":"Pattern Energy","article_publisher":"https:\/\/www.facebook.com\/PatternEnergy\/","article_published_time":"2020-05-14T01:28:31+00:00","article_modified_time":"2026-03-12T01:20:45+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/hike-up-hill.jpg","type":"image\/jpeg"}],"author":"ptrndmn","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"ptrndmn","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/patternenergy.com\/fr\/une-falaise-des-serpents-et-des-cactus\/#article","isPartOf":{"@id":"https:\/\/patternenergy.com\/fr\/une-falaise-des-serpents-et-des-cactus\/"},"author":{"name":"ptrndmn","@id":"https:\/\/patternenergy.com\/fr\/#\/schema\/person\/33965a118f27fded0be086c056aa2706"},"headline":"Une falaise, des serpents et des cactus !","datePublished":"2020-05-14T01:28:31+00:00","dateModified":"2026-03-12T01:20:45+00:00","mainEntityOfPage":{"@id":"https:\/\/patternenergy.com\/fr\/une-falaise-des-serpents-et-des-cactus\/"},"wordCount":1924,"publisher":{"@id":"https:\/\/patternenergy.com\/fr\/#organization"},"image":{"@id":"https:\/\/patternenergy.com\/fr\/une-falaise-des-serpents-et-des-cactus\/#primaryimage"},"thumbnailUrl":"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/hike-up-hill.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/patternenergy.com\/fr\/une-falaise-des-serpents-et-des-cactus\/","url":"https:\/\/patternenergy.com\/fr\/une-falaise-des-serpents-et-des-cactus\/","name":"Une falaise, des serpents et des cactus ! - Pattern Energy","isPartOf":{"@id":"https:\/\/patternenergy.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/patternenergy.com\/fr\/une-falaise-des-serpents-et-des-cactus\/#primaryimage"},"image":{"@id":"https:\/\/patternenergy.com\/fr\/une-falaise-des-serpents-et-des-cactus\/#primaryimage"},"thumbnailUrl":"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/hike-up-hill.jpg","datePublished":"2020-05-14T01:28:31+00:00","dateModified":"2026-03-12T01:20:45+00:00","description":"Les plus perspicaces d'entre vous verront que j'ai choisi \"Eye Of The Sandias Loop Trail\" et qu'il est indiqu\u00e9 \"HARD\" (difficile) alors que les autres choix \u00e9taient indiqu\u00e9s \"EASY\" (facile).","breadcrumb":{"@id":"https:\/\/patternenergy.com\/fr\/une-falaise-des-serpents-et-des-cactus\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/patternenergy.com\/fr\/une-falaise-des-serpents-et-des-cactus\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/patternenergy.com\/fr\/une-falaise-des-serpents-et-des-cactus\/#primaryimage","url":"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/hike-up-hill.jpg","contentUrl":"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/09\/hike-up-hill.jpg","width":1200,"height":800,"caption":"Ever upwards"},{"@type":"BreadcrumbList","@id":"https:\/\/patternenergy.com\/fr\/une-falaise-des-serpents-et-des-cactus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/patternenergy.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Une falaise, des serpents et des cactus !"}]},{"@type":"WebSite","@id":"https:\/\/patternenergy.com\/fr\/#website","url":"https:\/\/patternenergy.com\/fr\/","name":"Pattern Energy","description":"Nous d\u00e9veloppons, construisons, poss\u00e9dons et exploitons des projets \u00e9oliens, solaires, de transport et de stockage d'\u00e9nergie de haute qualit\u00e9 dans le monde entier.","publisher":{"@id":"https:\/\/patternenergy.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/patternenergy.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/patternenergy.com\/fr\/#organization","name":"Pattern Energy","url":"https:\/\/patternenergy.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/patternenergy.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/01\/Pattern-Energy-Media-thumbnail-logo.jpg","contentUrl":"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/01\/Pattern-Energy-Media-thumbnail-logo.jpg","width":1200,"height":627,"caption":"Pattern Energy"},"image":{"@id":"https:\/\/patternenergy.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PatternEnergy\/","https:\/\/instagram.com\/patternenergy?utm_medium=copy_link","https:\/\/www.linkedin.com\/company\/pattern-energy","https:\/\/www.youtube.com\/user\/PatternEnergy?app=desktop","https:\/\/web.cauze.com\/company\/293"]},{"@type":"Person","@id":"https:\/\/patternenergy.com\/fr\/#\/schema\/person\/33965a118f27fded0be086c056aa2706","name":"ptrndmn","sameAs":["https:\/\/patternenergy.com"],"url":"https:\/\/patternenergy.com\/fr\/author\/ptrndmn\/"}]}},"_links":{"self":[{"href":"https:\/\/patternenergy.com\/fr\/wp-json\/wp\/v2\/posts\/18241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/patternenergy.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patternenergy.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patternenergy.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/patternenergy.com\/fr\/wp-json\/wp\/v2\/comments?post=18241"}],"version-history":[{"count":0,"href":"https:\/\/patternenergy.com\/fr\/wp-json\/wp\/v2\/posts\/18241\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/patternenergy.com\/fr\/wp-json\/wp\/v2\/media\/13531"}],"wp:attachment":[{"href":"https:\/\/patternenergy.com\/fr\/wp-json\/wp\/v2\/media?parent=18241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patternenergy.com\/fr\/wp-json\/wp\/v2\/categories?post=18241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patternenergy.com\/fr\/wp-json\/wp\/v2\/tags?post=18241"},{"taxonomy":"sub_site","embeddable":true,"href":"https:\/\/patternenergy.com\/fr\/wp-json\/wp\/v2\/sub_site?post=18241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}