{"id":17906,"date":"2021-07-14T12:58:17","date_gmt":"2021-07-14T17:58:17","guid":{"rendered":"https:\/\/patternenergy.com\/tournesols-vent-et-bonheur-les-jacksons\/"},"modified":"2026-02-19T03:58:59","modified_gmt":"2026-02-19T08:58:59","slug":"tournesols-vent-et-bonheur-les-jacksons","status":"publish","type":"post","link":"https:\/\/patternenergy.com\/fr\/tournesols-vent-et-bonheur-les-jacksons\/","title":{"rendered":"Tournesols, vent et bonheur : Les Jacksons"},"content":{"rendered":"&#13;\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"880\" height=\"478\" class=\"wp-image-3213\" src=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2021\/12\/1_9.jpg\" alt=\"\"\/>&#13;\n<figcaption><strong><em>Des tournesols, des abeilles, du vent et du bonheur.<\/em><\/strong><\/figcaption>&#13;\n<\/figure>&#13;\n&#13;\n<p>\u00ab\u00a0Si nous avions besoin de voir des tournesols, c&rsquo;est cette ann\u00e9e\u00a0\u00bb, dit Martha avec un l\u00e9ger rire qui, au t\u00e9l\u00e9phone, ressemblait plus \u00e0 un sourire. Je me suis retrouv\u00e9e \u00e0 sourire et \u00e0 rire avec elle et son mari, Manley, \u00e0 la fin de notre rencontre.<\/p>&#13;\n&#13;\n<p>Voici Manley et Martha Jackson, propri\u00e9taires terriens \u00e0 Blenheim, en Ontario.<\/p>&#13;\n&#13;\n<p>Les Jackson ont eu une vie int\u00e9ressante et ont longtemps pratiqu\u00e9 l&rsquo;agriculture, effectuant tous les travaux et faisant face \u00e0 tous les maux de t\u00eate, les d\u00e9fis et le stress qui en d\u00e9coulent.<\/p>&#13;\n&#13;\n<p>\u00ab\u00a0Ensuite, nous avons perdu un membre de notre famille\u00a0\u00bb, a d\u00e9clar\u00e9 Martha, \u00ab\u00a0et cela a vraiment donn\u00e9 une autre perspective \u00e0 la vie. Apr\u00e8s une telle exp\u00e9rience, on commence \u00e0 voir les choses diff\u00e9remment et \u00e0 d\u00e9cider de ce qui est important.\u00a0\u00bb<\/p>&#13;\n&#13;\n<p>Il est bien connu que les personnes qui subissent une perte importante ou une trag\u00e9die changent souvent de vie, et les Jacksons l&rsquo;ont fait avec brio. Au lieu de travailler trop dur et de ne pas avoir le temps de profiter des fruits de leur travail, ils ont d\u00e9cid\u00e9 de devenir m\u00e9tayers, ce qui leur a permis de mener une vie heureuse sur leur terre et de l&rsquo;appr\u00e9cier \u00e0 sa juste valeur.<\/p>&#13;\n&#13;\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"880\" height=\"478\" class=\"wp-image-3214\" src=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2021\/12\/12.jpg\" alt=\"\"\/>&#13;\n<figcaption><strong><em>Manley et Martha<\/em><\/strong><\/figcaption>&#13;\n<\/figure>&#13;\n&#13;\n<p><strong>Le m\u00e9tayage<\/strong><\/p>&#13;\n&#13;\n<p>Pour un citadin comme moi, qui d\u00e9couvre son propre amour d&rsquo;une vie moins stressante, j&rsquo;avais quelques choses \u00e0 apprendre sur le m\u00e9tayage, et les Jackson ont eu la gentillesse de partager avec moi. Je dois dire que ce n&rsquo;est pas une mauvaise fa\u00e7on de vivre.<\/p>&#13;\n&#13;\n<p>Voici comment cela fonctionne : Les Jackson sont propri\u00e9taires de leur terrain et concluent des accords commerciaux avec d&rsquo;autres propri\u00e9taires d&rsquo;entreprises susceptibles de l&rsquo;utiliser. C&rsquo;est une activit\u00e9 tr\u00e8s entrepreneuriale et j&rsquo;ai \u00e9t\u00e9 fascin\u00e9e par la fa\u00e7on dont ils ont pu combiner plusieurs types d&rsquo;agriculture (et de revenus) sur leurs terres, sans effectuer eux-m\u00eames tous les travaux physiques.<\/p>&#13;\n&#13;\n<p>\u00ab\u00a0Nous pratiquons la rotation de nos terres\u00a0\u00bb, explique M. Manley, \u00ab\u00a0ce qui signifie que chaque partie de l&rsquo;exploitation n&rsquo;a pas n\u00e9cessairement des cultures qui poussent chaque ann\u00e9e. C&rsquo;est un moyen plus efficace de maintenir la productivit\u00e9 de la terre, et c&rsquo;est \u00e9galement bon pour la sant\u00e9 g\u00e9n\u00e9rale de la terre et de l&rsquo;environnement.\u00a0\u00bb<\/p>&#13;\n&#13;\n<p>Cette ann\u00e9e, les Jackson ont pass\u00e9 un accord avec un producteur de tournesols et nous avons commenc\u00e9 \u00e0 parler des diff\u00e9rents produits issus des tournesols, puis j&rsquo;ai d\u00fb les arr\u00eater.<\/p>&#13;\n&#13;\n<p>\u00ab\u00a0Tu sais, je trouve que les tournesols sont jolis, mais une fois, j&rsquo;\u00e9tais seule dans un champ de tournesols, ils \u00e9taient aussi grands que des personnes, et je pouvais jurer qu&rsquo;ils me regardaient.<\/p>&#13;\n&#13;\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"880\" height=\"478\" class=\"wp-image-3215\" src=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2021\/12\/10.jpg\" alt=\"\"\/>&#13;\n<figcaption><strong><em>Champ de tournesols<\/em><\/strong><\/figcaption>&#13;\n<\/figure>&#13;\n&#13;\n<p>Il y a eu une pause au t\u00e9l\u00e9phone, puis Manley a dit : \u00ab\u00a0Vous \u00eates de la ville\u00a0\u00bb, et nous avons tous recommenc\u00e9 \u00e0 rire.<\/p>&#13;\n&#13;\n<p>Martha a r\u00e9pondu que oui, les tournesols peuvent atteindre jusqu&rsquo;\u00e0 deux m\u00e8tres de haut et qu&rsquo;ils sont magnifiques \u00e0 voir. (Comme tous ceux qui nous lisent peuvent le constater sur les photos).<\/p>&#13;\n&#13;\n<figure class=\"wp-block-pullquote\">&#13;\n<blockquote>&#13;\n<p>Si nous avions besoin de voir des tournesols, c&rsquo;est cette ann\u00e9e.<\/p>&#13;\n<\/blockquote>&#13;\n<\/figure>&#13;\n&#13;\n<p><strong>Les abeilles et le vent<\/strong><\/p>&#13;\n&#13;\n<p>En plus des tournesols, un apiculteur charge ses ruches sur un camion \u00e0 plateau, les conduit jusqu&rsquo;\u00e0 la propri\u00e9t\u00e9 des Jackson et les laisse faire ce que font les abeilles, ce qu&rsquo;elles appr\u00e9cient \u00e9galement. \u00ab\u00a0Des amis de la famille\u00a0\u00bb, m&rsquo;a dit Martha.<\/p>&#13;\n&#13;\n<p>Enfin, les Jacksons exploitent l&rsquo;\u00e9nergie \u00e9olienne. \u00ab\u00a0Le fait d&rsquo;avoir des \u00e9oliennes sur notre propri\u00e9t\u00e9 a \u00e9t\u00e9 formidable\u00a0\u00bb, a d\u00e9clar\u00e9 Martha. \u00ab\u00a0Pattern a des gens sympathiques avec lesquels nous aimons vraiment travailler. Parfois, Kevin, le chef de secteur, passe nous voir pour voir comment nous nous d\u00e9brouillons, et Pat a \u00e9t\u00e9 ph\u00e9nom\u00e9nal. Nous nous rendons g\u00e9n\u00e9ralement \u00e0 Wind Lane tous les jours. Nous aimons voir les \u00e9oliennes en action et nous pensons que c&rsquo;est une exp\u00e9rience formidable.<\/p>&#13;\n&#13;\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"880\" height=\"478\" class=\"wp-image-3216\" src=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2021\/12\/11.jpg\" alt=\"\"\/>&#13;\n<figcaption><em><strong>Vue des \u00e9oliennes depuis le champ de tournesols.  <\/strong><\/em><\/figcaption>&#13;\n<\/figure>&#13;\n&#13;\n<p>Nous arrivions \u00e0 la fin de notre conversation, et Martha et Manley ont tous deux partag\u00e9 quelques autres r\u00e9flexions sur la production d&rsquo;\u00e9nergie \u00e9olienne et le r\u00f4le qu&rsquo;ils y ont jou\u00e9. \u00ab\u00a0C&rsquo;est vraiment dans l&rsquo;int\u00e9r\u00eat de tout le monde\u00a0\u00bb, a d\u00e9clar\u00e9 Martha. \u00ab\u00a0De plus, ajoute M. Manley, Pattern est un grand partenaire communautaire qui ne se limite pas \u00e0 l&rsquo;\u00e9nergie \u00e9olienne et qui a fait une \u00e9norme diff\u00e9rence dans notre communaut\u00e9. Ils soutiennent leurs principes, et nous appr\u00e9cions vraiment cela\u00a0\u00bb.<\/p>&#13;\n&#13;\n<p>Alors que notre entretien touchait \u00e0 sa fin, nous n&rsquo;avons pas pu \u00e9viter de parler de nos espoirs d&rsquo;une meilleure situation mondiale \u00e0 l&rsquo;avenir.<\/p>&#13;\n&#13;\n<p>Nous sommes rest\u00e9s silencieux pendant quelques instants, puis Martha a dit : \u00ab\u00a0Si nous avions besoin de voir des tournesols, c&rsquo;est cette ann\u00e9e\u00a0\u00bb.<\/p>&#13;\n&#13;\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"880\" height=\"478\" class=\"wp-image-3217\" src=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2021\/12\/1_8.jpg\" alt=\"\"\/>&#13;\n<figcaption><strong><em>Tournesols en pleine floraison.<\/em><\/strong><\/figcaption>&#13;\n<\/figure>&#13;\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0Si nous avions besoin de voir des tournesols, c&rsquo;est cette ann\u00e9e\u00a0\u00bb, dit Martha avec un l\u00e9ger rire qui, au t\u00e9l\u00e9phone, ressemblait plus \u00e0 un sourire. Je me suis retrouv\u00e9e \u00e0 sourire et \u00e0 rire avec elle et son mari, Manley, \u00e0 la fin de notre rencontre.  <\/p>\n","protected":false},"author":3,"featured_media":10441,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[511,644,448],"tags":[690],"sub_site":[],"class_list":["post-17906","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-canada-fr","category-histoires-de-pattern-canada","category-non-classifiee","tag-vent-du-sud-du-kent"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tournesols, vent et bonheur : Les Jacksons - Pattern Energy<\/title>\n<meta name=\"description\" content=\"&quot;Si nous avions besoin de voir des tournesols, c&#039;est cette ann\u00e9e&quot;, a d\u00e9clar\u00e9 Martha avec un l\u00e9ger rire qui ressemblait plus \u00e0 un sourire au t\u00e9l\u00e9phone, et je me suis surprise \u00e0 sourire et \u00e0 rire avec elle et son mari, Manley.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/patternenergy.com\/fr\/tournesols-vent-et-bonheur-les-jacksons\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tournesols, vent et bonheur : Les Jacksons - Pattern Energy\" \/>\n<meta property=\"og:description\" content=\"&quot;Si nous avions besoin de voir des tournesols, c&#039;est cette ann\u00e9e&quot;, a d\u00e9clar\u00e9 Martha avec un l\u00e9ger rire qui ressemblait plus \u00e0 un sourire au t\u00e9l\u00e9phone, et je me suis surprise \u00e0 sourire et \u00e0 rire avec elle et son mari, Manley.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/patternenergy.com\/fr\/tournesols-vent-et-bonheur-les-jacksons\/\" \/>\n<meta property=\"og:site_name\" content=\"Pattern Energy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PatternEnergy\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-14T17:58:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-19T08:58:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2021\/07\/Pattern-CAN-Featured-Images-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"672\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alisa Frincke\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alisa Frincke\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/tournesols-vent-et-bonheur-les-jacksons\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/tournesols-vent-et-bonheur-les-jacksons\\\/\"},\"author\":{\"name\":\"Alisa Frincke\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/#\\\/schema\\\/person\\\/6f7080f7c9428a32a6bbe73bf6c8e412\"},\"headline\":\"Tournesols, vent et bonheur : Les Jacksons\",\"datePublished\":\"2021-07-14T17:58:17+00:00\",\"dateModified\":\"2026-02-19T08:58:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/tournesols-vent-et-bonheur-les-jacksons\\\/\"},\"wordCount\":849,\"publisher\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/tournesols-vent-et-bonheur-les-jacksons\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/patternenergy.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Pattern-CAN-Featured-Images-2.jpg\",\"keywords\":[\"Vent du sud du Kent\"],\"articleSection\":[\"Canada\",\"Histoires de Pattern Canada\",\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/tournesols-vent-et-bonheur-les-jacksons\\\/\",\"url\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/tournesols-vent-et-bonheur-les-jacksons\\\/\",\"name\":\"Tournesols, vent et bonheur : Les Jacksons - Pattern Energy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/tournesols-vent-et-bonheur-les-jacksons\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/tournesols-vent-et-bonheur-les-jacksons\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/patternenergy.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Pattern-CAN-Featured-Images-2.jpg\",\"datePublished\":\"2021-07-14T17:58:17+00:00\",\"dateModified\":\"2026-02-19T08:58:59+00:00\",\"description\":\"\\\"Si nous avions besoin de voir des tournesols, c'est cette ann\u00e9e\\\", a d\u00e9clar\u00e9 Martha avec un l\u00e9ger rire qui ressemblait plus \u00e0 un sourire au t\u00e9l\u00e9phone, et je me suis surprise \u00e0 sourire et \u00e0 rire avec elle et son mari, Manley.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/tournesols-vent-et-bonheur-les-jacksons\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/patternenergy.com\\\/fr\\\/tournesols-vent-et-bonheur-les-jacksons\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/tournesols-vent-et-bonheur-les-jacksons\\\/#primaryimage\",\"url\":\"https:\\\/\\\/patternenergy.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Pattern-CAN-Featured-Images-2.jpg\",\"contentUrl\":\"https:\\\/\\\/patternenergy.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Pattern-CAN-Featured-Images-2.jpg\",\"width\":1080,\"height\":672},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/tournesols-vent-et-bonheur-les-jacksons\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tournesols, vent et bonheur : Les Jacksons\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/\",\"name\":\"Pattern Energy\",\"description\":\"Nous d\u00e9veloppons, construisons, poss\u00e9dons et exploitons des projets \u00e9oliens, solaires, de transport et de stockage d'\u00e9nergie de haute qualit\u00e9 dans le monde entier.\",\"publisher\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/#organization\",\"name\":\"Pattern Energy\",\"url\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/patternenergy.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Pattern-Energy-Media-thumbnail-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/patternenergy.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Pattern-Energy-Media-thumbnail-logo.jpg\",\"width\":1200,\"height\":627,\"caption\":\"Pattern Energy\"},\"image\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PatternEnergy\\\/\",\"https:\\\/\\\/instagram.com\\\/patternenergy?utm_medium=copy_link\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pattern-energy\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/PatternEnergy?app=desktop\",\"https:\\\/\\\/web.cauze.com\\\/company\\\/293\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/#\\\/schema\\\/person\\\/6f7080f7c9428a32a6bbe73bf6c8e412\",\"name\":\"Alisa Frincke\",\"url\":\"https:\\\/\\\/patternenergy.com\\\/fr\\\/author\\\/alisa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tournesols, vent et bonheur : Les Jacksons - Pattern Energy","description":"\"Si nous avions besoin de voir des tournesols, c'est cette ann\u00e9e\", a d\u00e9clar\u00e9 Martha avec un l\u00e9ger rire qui ressemblait plus \u00e0 un sourire au t\u00e9l\u00e9phone, et je me suis surprise \u00e0 sourire et \u00e0 rire avec elle et son mari, Manley.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/patternenergy.com\/fr\/tournesols-vent-et-bonheur-les-jacksons\/","og_locale":"fr_FR","og_type":"article","og_title":"Tournesols, vent et bonheur : Les Jacksons - Pattern Energy","og_description":"\"Si nous avions besoin de voir des tournesols, c'est cette ann\u00e9e\", a d\u00e9clar\u00e9 Martha avec un l\u00e9ger rire qui ressemblait plus \u00e0 un sourire au t\u00e9l\u00e9phone, et je me suis surprise \u00e0 sourire et \u00e0 rire avec elle et son mari, Manley.","og_url":"https:\/\/patternenergy.com\/fr\/tournesols-vent-et-bonheur-les-jacksons\/","og_site_name":"Pattern Energy","article_publisher":"https:\/\/www.facebook.com\/PatternEnergy\/","article_published_time":"2021-07-14T17:58:17+00:00","article_modified_time":"2026-02-19T08:58:59+00:00","og_image":[{"width":1080,"height":672,"url":"https:\/\/patternenergy.com\/wp-content\/uploads\/2021\/07\/Pattern-CAN-Featured-Images-2.jpg","type":"image\/jpeg"}],"author":"Alisa Frincke","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Alisa Frincke","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/patternenergy.com\/fr\/tournesols-vent-et-bonheur-les-jacksons\/#article","isPartOf":{"@id":"https:\/\/patternenergy.com\/fr\/tournesols-vent-et-bonheur-les-jacksons\/"},"author":{"name":"Alisa Frincke","@id":"https:\/\/patternenergy.com\/fr\/#\/schema\/person\/6f7080f7c9428a32a6bbe73bf6c8e412"},"headline":"Tournesols, vent et bonheur : Les Jacksons","datePublished":"2021-07-14T17:58:17+00:00","dateModified":"2026-02-19T08:58:59+00:00","mainEntityOfPage":{"@id":"https:\/\/patternenergy.com\/fr\/tournesols-vent-et-bonheur-les-jacksons\/"},"wordCount":849,"publisher":{"@id":"https:\/\/patternenergy.com\/fr\/#organization"},"image":{"@id":"https:\/\/patternenergy.com\/fr\/tournesols-vent-et-bonheur-les-jacksons\/#primaryimage"},"thumbnailUrl":"https:\/\/patternenergy.com\/wp-content\/uploads\/2021\/07\/Pattern-CAN-Featured-Images-2.jpg","keywords":["Vent du sud du Kent"],"articleSection":["Canada","Histoires de Pattern Canada","Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/patternenergy.com\/fr\/tournesols-vent-et-bonheur-les-jacksons\/","url":"https:\/\/patternenergy.com\/fr\/tournesols-vent-et-bonheur-les-jacksons\/","name":"Tournesols, vent et bonheur : Les Jacksons - Pattern Energy","isPartOf":{"@id":"https:\/\/patternenergy.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/patternenergy.com\/fr\/tournesols-vent-et-bonheur-les-jacksons\/#primaryimage"},"image":{"@id":"https:\/\/patternenergy.com\/fr\/tournesols-vent-et-bonheur-les-jacksons\/#primaryimage"},"thumbnailUrl":"https:\/\/patternenergy.com\/wp-content\/uploads\/2021\/07\/Pattern-CAN-Featured-Images-2.jpg","datePublished":"2021-07-14T17:58:17+00:00","dateModified":"2026-02-19T08:58:59+00:00","description":"\"Si nous avions besoin de voir des tournesols, c'est cette ann\u00e9e\", a d\u00e9clar\u00e9 Martha avec un l\u00e9ger rire qui ressemblait plus \u00e0 un sourire au t\u00e9l\u00e9phone, et je me suis surprise \u00e0 sourire et \u00e0 rire avec elle et son mari, Manley.","breadcrumb":{"@id":"https:\/\/patternenergy.com\/fr\/tournesols-vent-et-bonheur-les-jacksons\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/patternenergy.com\/fr\/tournesols-vent-et-bonheur-les-jacksons\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/patternenergy.com\/fr\/tournesols-vent-et-bonheur-les-jacksons\/#primaryimage","url":"https:\/\/patternenergy.com\/wp-content\/uploads\/2021\/07\/Pattern-CAN-Featured-Images-2.jpg","contentUrl":"https:\/\/patternenergy.com\/wp-content\/uploads\/2021\/07\/Pattern-CAN-Featured-Images-2.jpg","width":1080,"height":672},{"@type":"BreadcrumbList","@id":"https:\/\/patternenergy.com\/fr\/tournesols-vent-et-bonheur-les-jacksons\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/patternenergy.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Tournesols, vent et bonheur : Les Jacksons"}]},{"@type":"WebSite","@id":"https:\/\/patternenergy.com\/fr\/#website","url":"https:\/\/patternenergy.com\/fr\/","name":"Pattern Energy","description":"Nous d\u00e9veloppons, construisons, poss\u00e9dons et exploitons des projets \u00e9oliens, solaires, de transport et de stockage d'\u00e9nergie de haute qualit\u00e9 dans le monde entier.","publisher":{"@id":"https:\/\/patternenergy.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/patternenergy.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/patternenergy.com\/fr\/#organization","name":"Pattern Energy","url":"https:\/\/patternenergy.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/patternenergy.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/01\/Pattern-Energy-Media-thumbnail-logo.jpg","contentUrl":"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/01\/Pattern-Energy-Media-thumbnail-logo.jpg","width":1200,"height":627,"caption":"Pattern Energy"},"image":{"@id":"https:\/\/patternenergy.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PatternEnergy\/","https:\/\/instagram.com\/patternenergy?utm_medium=copy_link","https:\/\/www.linkedin.com\/company\/pattern-energy","https:\/\/www.youtube.com\/user\/PatternEnergy?app=desktop","https:\/\/web.cauze.com\/company\/293"]},{"@type":"Person","@id":"https:\/\/patternenergy.com\/fr\/#\/schema\/person\/6f7080f7c9428a32a6bbe73bf6c8e412","name":"Alisa Frincke","url":"https:\/\/patternenergy.com\/fr\/author\/alisa\/"}]}},"_links":{"self":[{"href":"https:\/\/patternenergy.com\/fr\/wp-json\/wp\/v2\/posts\/17906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/patternenergy.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patternenergy.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patternenergy.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/patternenergy.com\/fr\/wp-json\/wp\/v2\/comments?post=17906"}],"version-history":[{"count":0,"href":"https:\/\/patternenergy.com\/fr\/wp-json\/wp\/v2\/posts\/17906\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/patternenergy.com\/fr\/wp-json\/wp\/v2\/media\/10441"}],"wp:attachment":[{"href":"https:\/\/patternenergy.com\/fr\/wp-json\/wp\/v2\/media?parent=17906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patternenergy.com\/fr\/wp-json\/wp\/v2\/categories?post=17906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patternenergy.com\/fr\/wp-json\/wp\/v2\/tags?post=17906"},{"taxonomy":"sub_site","embeddable":true,"href":"https:\/\/patternenergy.com\/fr\/wp-json\/wp\/v2\/sub_site?post=17906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}