{"id":18591,"date":"2023-07-11T07:46:58","date_gmt":"2023-07-11T12:46:58","guid":{"rendered":"https:\/\/patternenergy.com\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\/"},"modified":"2026-01-19T13:39:37","modified_gmt":"2026-01-19T18:39:37","slug":"pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta","status":"publish","type":"post","link":"https:\/\/patternenergy.com\/es\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\/","title":{"rendered":"Pattern Energy inicia las operaciones del proyecto e\u00f3lico de Lanfine (Alberta)"},"content":{"rendered":"<p><strong><em>Una instalaci\u00f3n de 150 MW generar\u00e1 energ\u00eda limpia para hasta 30.000 hogares de Alberta  <\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>West Oyen, Alberta, Canad\u00e1, 11 de julio de 2023<\/strong> &#8211; Pattern Energy Group LP (Pattern Energy), l\u00edder en energ\u00edas renovables e infraestructuras de transmisi\u00f3n, ha anunciado hoy que ha finalizado la construcci\u00f3n e iniciado la explotaci\u00f3n de su proyecto de energ\u00eda e\u00f3lica Lanfine de 150 megavatios (MW) en Alberta, Canad\u00e1.<\/p>\n<p>\u00abComo uno de los mayores operadores de energ\u00eda e\u00f3lica de <span class=\"xn-location\">Canad\u00e1<\/span>, Pattern sigue ampliando su presencia con su primera instalaci\u00f3n en <span class=\"xn-location\">Alberta<\/span>\u00ab, declar\u00f3 <span class=\"xn-person\">Hunter Armistead<\/span>, consejero delegado de Pattern Energy. \u00abLanfine Wind utiliza las turbinas m\u00e1s potentes de nuestra flota operativa, con unos impresionantes 4,3 MW cada una, que en total suministran energ\u00eda a 30.000 hogares de <span class=\"xn-location\">Alberta<\/span> cada a\u00f1o. En la \u00faltima d\u00e9cada, Pattern ha puesto en marcha 11 proyectos de energ\u00eda e\u00f3lica en cinco provincias de <span class=\"xn-location\">Canad\u00e1<\/span>, creando miles de puestos de trabajo en el pa\u00eds y millones de d\u00f3lares en beneficios econ\u00f3micos directos para nuestras comunidades locales\u00bb.<\/p>\n<div id=\"attachment_8538\" style=\"width: 1210px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-8538\" class=\"size-full wp-image-8538\" src=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2023\/07\/Picture1-Turbine.jpg\" alt=\"\" width=\"1200\" height=\"1001\" srcset=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2023\/07\/Picture1-Turbine.jpg 1200w, https:\/\/patternenergy.com\/wp-content\/uploads\/2023\/07\/Picture1-Turbine-300x250.jpg 300w, https:\/\/patternenergy.com\/wp-content\/uploads\/2023\/07\/Picture1-Turbine-1024x854.jpg 1024w, https:\/\/patternenergy.com\/wp-content\/uploads\/2023\/07\/Picture1-Turbine-768x641.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><p id=\"caption-attachment-8538\" class=\"wp-caption-text\">Instalaci\u00f3n e\u00f3lica Lanfine de Pattern Energy en Alberta<\/p><\/div>\n<p>El proyecto Lanfine Wind utiliza 35 turbinas Vestas V150 de 4,3 MW. Lanfine Wind ha firmado un acuerdo de compra de energ\u00eda con liquidaci\u00f3n financiera de 10 a\u00f1os con West Fraser, una empresa diversificada de productos de madera con m\u00e1s de 60 instalaciones en <span class=\"xn-location\">Canad\u00e1<\/span>, <span class=\"xn-location\">Estados Unidos<\/span>, <span class=\"xn-location\">Reino Unido<\/span> y <span class=\"xn-location\">Europa<\/span>, por aproximadamente el 50% de la producci\u00f3n de la instalaci\u00f3n, que apoya los esfuerzos de West Fraser por reducir sus emisiones de GEI de alcance 1 y 2 en un 46,2% para 2030.<\/p>\n<p>\u00abLa <span class=\"xn-location\">ciudad<\/span> de Oyen se congratula de seguir colaborando con Lanfine Wind, de Pattern Energy\u00bb, ha declarado el alcalde de Oyen <span class=\"xn-person\">, Doug Jones<\/span>. \u00abPattern Energy ha demostrado que quiere ser un buen vecino a largo plazo. Extendemos nuestra gratitud por todo el apoyo mostrado a nuestras empresas locales. El Programa de Beneficios Comunitarios de Lanfine Wind proporcionar\u00e1 un apoyo vital que tendr\u00e1 un impacto positivo largo y duradero en toda nuestra comunidad.\u00bb<\/p>\n<p>En mayo, Pattern Energy cerr\u00f3 con el National Bank of <span class=\"xn-location\">Canada<\/span> y Siemens Financial Services un proyecto de financiaci\u00f3n de aproximadamente <span class=\"xn-money\">220 millones de d\u00f3lares canadienses<\/span> basado en 20 a\u00f1os de flujos de caja para Lanfine Wind. Lanfine Wind representa una inversi\u00f3n total de unos <span class=\"xn-money\">335 millones de d\u00f3lares canadienses<\/span> en <span class=\"xn-location\">Alberta<\/span> que est\u00e1 contribuyendo a generar beneficios econ\u00f3micos duraderos y diversos.<\/p>\n<p>Aproximadamente 250 trabajadores estuvieron en el lugar durante el pico de actividad de la construcci\u00f3n, estimulando la demanda de empresas y servicios locales en la comunidad rural. La construcci\u00f3n del proyecto corri\u00f3 a cargo de Borea Construction.<\/p>\n<p>Adem\u00e1s de las oportunidades de empleo y contrataci\u00f3n, Lanfine Wind generar\u00e1 ingresos para los propietarios de las tierras y proporcionar\u00e1 ingresos fiscales a la comunidad local, lo que contribuir\u00e1 directamente a la educaci\u00f3n, los servicios comunitarios, las carreteras y las capacidades de primeros auxilios. Adem\u00e1s, un Programa de Beneficios Comunitarios financiado por el proyecto apoyar\u00e1 iniciativas locales y organizaciones comunitarias con un compromiso de <span class=\"xn-money\"> 2 millones de d\u00f3lares<\/span> durante los primeros 20 a\u00f1os de funcionamiento de Lanfine Wind.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_8539\" style=\"width: 1210px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-8539\" class=\"size-full wp-image-8539\" src=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2023\/07\/Picture2-crane.jpg\" alt=\"\" width=\"1200\" height=\"801\" srcset=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2023\/07\/Picture2-crane.jpg 1200w, https:\/\/patternenergy.com\/wp-content\/uploads\/2023\/07\/Picture2-crane-300x200.jpg 300w, https:\/\/patternenergy.com\/wp-content\/uploads\/2023\/07\/Picture2-crane-1024x684.jpg 1024w, https:\/\/patternenergy.com\/wp-content\/uploads\/2023\/07\/Picture2-crane-768x513.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><p id=\"caption-attachment-8539\" class=\"wp-caption-text\">Las turbinas de 4,3 MW de Lanfine Wind son las m\u00e1s potentes de la flota de Pattern Energy<\/p><\/div>\n<p>Con la incorporaci\u00f3n de Lanfine Wind, la cartera de Pattern Energy en <span class=\"xn-location\">Canad\u00e1<\/span> suma ya 11 instalaciones e\u00f3licas operativas en cinco provincias. Para m\u00e1s informaci\u00f3n, visite <a href=\"https:\/\/c212.net\/c\/link\/?t=0&amp;l=en&amp;o=3915927-1&amp;h=1715751051&amp;u=https%3A%2F%2Fpatterncanada.ca%2F&amp;a=patterncanada.com\" target=\"_blank\" rel=\"nofollow noopener\">patterncanada.com<\/a>.<\/p>\n<p><b>Acerca de Pattern Energy<br class=\"dnr\"><\/b>Pattern Energy es uno de los mayores promotores y operadores privados del mundo de proyectos e\u00f3licos, solares, de transmisi\u00f3n y de almacenamiento de energ\u00eda. Su cartera operativa incluye 38 instalaciones de energ\u00edas renovables que utilizan la mejor tecnolog\u00eda de su clase, con una capacidad operativa de m\u00e1s de 6.000 MW en <span class=\"xn-location\">Estados Unidos<\/span>, <span class=\"xn-location\">Canad\u00e1<\/span>, <span class=\"xn-location\">Jap\u00f3n<\/span> y <span class=\"xn-location\">M\u00e9xico<\/span>. Pattern Energy se gu\u00eda por el compromiso a largo plazo de servir a los clientes, proteger el medio ambiente y fortalecer las comunidades. Para m\u00e1s informaci\u00f3n, visite <a href=\"https:\/\/c212.net\/c\/link\/?t=0&amp;l=en&amp;o=3915927-1&amp;h=323972681&amp;u=http%3A%2F%2Fwww.patternenergy.com%2F&amp;a=www.patternenergy.com\" target=\"_blank\" rel=\"nofollow noopener\">www.patternenergy.com.<\/a><\/p>\n<p>Contacto:<br class=\"dnr\"><span class=\"xn-person\">Matt Dallas<\/span><br class=\"dnr\">Patr\u00f3n de Energ\u00eda<br class=\"dnr\">917-363-1333<br class=\"dnr\"><a href=\"mailto:matt.dallas@patternenergy.com\" target=\"_blank\" rel=\"nofollow noopener\">matt.dallas@patternenergy.<\/a><a href=\"mailto:matt.dallas@patternenergy.com\" target=\"_blank\" rel=\"nofollow noopener\">com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una instalaci\u00f3n de 150 MW generar\u00e1 energ\u00eda limpia para hasta 30.000 hogares de Alberta &nbsp; West Oyen, Alberta, Canad\u00e1, 11 de julio de 2023 &#8211; Pattern Energy Group LP (Pattern Energy), l\u00edder en energ\u00edas renovables e infraestructuras de transmisi\u00f3n, ha anunciado hoy que ha finalizado la construcci\u00f3n e iniciado la explotaci\u00f3n de su proyecto de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":16088,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[513,581],"tags":[625,849],"sub_site":[1348],"class_list":["post-18591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-canada-es","category-comunicado-de-prensa","tag-canada-es","tag-lanfine-wind-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pattern Energy inicia las operaciones del proyecto e\u00f3lico de Lanfine (Alberta) - Pattern Energy<\/title>\n<meta name=\"description\" content=\"Pattern Energy, l\u00edder en energ\u00edas renovables e infraestructuras de transmisi\u00f3n, ha anunciado hoy que ha finalizado la construcci\u00f3n e iniciado la explotaci\u00f3n de su proyecto e\u00f3lico de Lanfine, de 150 megavatios, en Alberta (Canad\u00e1).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/patternenergy.com\/es\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pattern Energy inicia las operaciones del proyecto e\u00f3lico de Lanfine (Alberta) - Pattern Energy\" \/>\n<meta property=\"og:description\" content=\"Pattern Energy, l\u00edder en energ\u00edas renovables e infraestructuras de transmisi\u00f3n, ha anunciado hoy que ha finalizado la construcci\u00f3n e iniciado la explotaci\u00f3n de su proyecto e\u00f3lico de Lanfine, de 150 megavatios, en Alberta (Canad\u00e1).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/patternenergy.com\/es\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\/\" \/>\n<meta property=\"og:site_name\" content=\"Pattern Energy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PatternEnergy\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-11T12:46:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-19T18:39:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2023\/07\/Picture1-Turbine.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1001\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alisa Frincke\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alisa Frincke\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\\\/\"},\"author\":{\"name\":\"Alisa Frincke\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/#\\\/schema\\\/person\\\/6f7080f7c9428a32a6bbe73bf6c8e412\"},\"headline\":\"Pattern Energy inicia las operaciones del proyecto e\u00f3lico de Lanfine (Alberta)\",\"datePublished\":\"2023-07-11T12:46:58+00:00\",\"dateModified\":\"2026-01-19T18:39:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\\\/\"},\"wordCount\":716,\"publisher\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/patternenergy.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Picture1-Turbine.jpg\",\"keywords\":[\"Canad\u00e1\",\"Lanfine Wind\"],\"articleSection\":[\"Canad\u00e1\",\"Comunicado de prensa\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\\\/\",\"url\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\\\/\",\"name\":\"Pattern Energy inicia las operaciones del proyecto e\u00f3lico de Lanfine (Alberta) - Pattern Energy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/patternenergy.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Picture1-Turbine.jpg\",\"datePublished\":\"2023-07-11T12:46:58+00:00\",\"dateModified\":\"2026-01-19T18:39:37+00:00\",\"description\":\"Pattern Energy, l\u00edder en energ\u00edas renovables e infraestructuras de transmisi\u00f3n, ha anunciado hoy que ha finalizado la construcci\u00f3n e iniciado la explotaci\u00f3n de su proyecto e\u00f3lico de Lanfine, de 150 megavatios, en Alberta (Canad\u00e1).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/patternenergy.com\\\/es\\\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/patternenergy.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Picture1-Turbine.jpg\",\"contentUrl\":\"https:\\\/\\\/patternenergy.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Picture1-Turbine.jpg\",\"width\":1200,\"height\":1001,\"caption\":\"Pattern Energy\u2019s Lanfine Wind facility in Alberta\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pattern Energy inicia las operaciones del proyecto e\u00f3lico de Lanfine (Alberta)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/\",\"name\":\"Pattern Energy\",\"description\":\"Desarrollamos, construimos, poseemos y explotamos proyectos e\u00f3licos, solares, de transmisi\u00f3n y de almacenamiento de energ\u00eda de alta calidad en todo el mundo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/#organization\",\"name\":\"Pattern Energy\",\"url\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/patternenergy.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Pattern-Energy-Media-thumbnail-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/patternenergy.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Pattern-Energy-Media-thumbnail-logo.jpg\",\"width\":1200,\"height\":627,\"caption\":\"Pattern Energy\"},\"image\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PatternEnergy\\\/\",\"https:\\\/\\\/instagram.com\\\/patternenergy?utm_medium=copy_link\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pattern-energy\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/PatternEnergy?app=desktop\",\"https:\\\/\\\/web.cauze.com\\\/company\\\/293\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/#\\\/schema\\\/person\\\/6f7080f7c9428a32a6bbe73bf6c8e412\",\"name\":\"Alisa Frincke\",\"url\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/author\\\/alisa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pattern Energy inicia las operaciones del proyecto e\u00f3lico de Lanfine (Alberta) - Pattern Energy","description":"Pattern Energy, l\u00edder en energ\u00edas renovables e infraestructuras de transmisi\u00f3n, ha anunciado hoy que ha finalizado la construcci\u00f3n e iniciado la explotaci\u00f3n de su proyecto e\u00f3lico de Lanfine, de 150 megavatios, en Alberta (Canad\u00e1).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/patternenergy.com\/es\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\/","og_locale":"es_ES","og_type":"article","og_title":"Pattern Energy inicia las operaciones del proyecto e\u00f3lico de Lanfine (Alberta) - Pattern Energy","og_description":"Pattern Energy, l\u00edder en energ\u00edas renovables e infraestructuras de transmisi\u00f3n, ha anunciado hoy que ha finalizado la construcci\u00f3n e iniciado la explotaci\u00f3n de su proyecto e\u00f3lico de Lanfine, de 150 megavatios, en Alberta (Canad\u00e1).","og_url":"https:\/\/patternenergy.com\/es\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\/","og_site_name":"Pattern Energy","article_publisher":"https:\/\/www.facebook.com\/PatternEnergy\/","article_published_time":"2023-07-11T12:46:58+00:00","article_modified_time":"2026-01-19T18:39:37+00:00","og_image":[{"width":1200,"height":1001,"url":"https:\/\/patternenergy.com\/wp-content\/uploads\/2023\/07\/Picture1-Turbine.jpg","type":"image\/jpeg"}],"author":"Alisa Frincke","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Alisa Frincke","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/patternenergy.com\/es\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\/#article","isPartOf":{"@id":"https:\/\/patternenergy.com\/es\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\/"},"author":{"name":"Alisa Frincke","@id":"https:\/\/patternenergy.com\/es\/#\/schema\/person\/6f7080f7c9428a32a6bbe73bf6c8e412"},"headline":"Pattern Energy inicia las operaciones del proyecto e\u00f3lico de Lanfine (Alberta)","datePublished":"2023-07-11T12:46:58+00:00","dateModified":"2026-01-19T18:39:37+00:00","mainEntityOfPage":{"@id":"https:\/\/patternenergy.com\/es\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\/"},"wordCount":716,"publisher":{"@id":"https:\/\/patternenergy.com\/es\/#organization"},"image":{"@id":"https:\/\/patternenergy.com\/es\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\/#primaryimage"},"thumbnailUrl":"https:\/\/patternenergy.com\/wp-content\/uploads\/2023\/07\/Picture1-Turbine.jpg","keywords":["Canad\u00e1","Lanfine Wind"],"articleSection":["Canad\u00e1","Comunicado de prensa"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/patternenergy.com\/es\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\/","url":"https:\/\/patternenergy.com\/es\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\/","name":"Pattern Energy inicia las operaciones del proyecto e\u00f3lico de Lanfine (Alberta) - Pattern Energy","isPartOf":{"@id":"https:\/\/patternenergy.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/patternenergy.com\/es\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\/#primaryimage"},"image":{"@id":"https:\/\/patternenergy.com\/es\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\/#primaryimage"},"thumbnailUrl":"https:\/\/patternenergy.com\/wp-content\/uploads\/2023\/07\/Picture1-Turbine.jpg","datePublished":"2023-07-11T12:46:58+00:00","dateModified":"2026-01-19T18:39:37+00:00","description":"Pattern Energy, l\u00edder en energ\u00edas renovables e infraestructuras de transmisi\u00f3n, ha anunciado hoy que ha finalizado la construcci\u00f3n e iniciado la explotaci\u00f3n de su proyecto e\u00f3lico de Lanfine, de 150 megavatios, en Alberta (Canad\u00e1).","breadcrumb":{"@id":"https:\/\/patternenergy.com\/es\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/patternenergy.com\/es\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patternenergy.com\/es\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\/#primaryimage","url":"https:\/\/patternenergy.com\/wp-content\/uploads\/2023\/07\/Picture1-Turbine.jpg","contentUrl":"https:\/\/patternenergy.com\/wp-content\/uploads\/2023\/07\/Picture1-Turbine.jpg","width":1200,"height":1001,"caption":"Pattern Energy\u2019s Lanfine Wind facility in Alberta"},{"@type":"BreadcrumbList","@id":"https:\/\/patternenergy.com\/es\/pattern-energy-inicia-las-operaciones-del-proyecto-eolico-de-lanfine-alberta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/patternenergy.com\/es\/"},{"@type":"ListItem","position":2,"name":"Pattern Energy inicia las operaciones del proyecto e\u00f3lico de Lanfine (Alberta)"}]},{"@type":"WebSite","@id":"https:\/\/patternenergy.com\/es\/#website","url":"https:\/\/patternenergy.com\/es\/","name":"Pattern Energy","description":"Desarrollamos, construimos, poseemos y explotamos proyectos e\u00f3licos, solares, de transmisi\u00f3n y de almacenamiento de energ\u00eda de alta calidad en todo el mundo.","publisher":{"@id":"https:\/\/patternenergy.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/patternenergy.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/patternenergy.com\/es\/#organization","name":"Pattern Energy","url":"https:\/\/patternenergy.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patternenergy.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/01\/Pattern-Energy-Media-thumbnail-logo.jpg","contentUrl":"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/01\/Pattern-Energy-Media-thumbnail-logo.jpg","width":1200,"height":627,"caption":"Pattern Energy"},"image":{"@id":"https:\/\/patternenergy.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PatternEnergy\/","https:\/\/instagram.com\/patternenergy?utm_medium=copy_link","https:\/\/www.linkedin.com\/company\/pattern-energy","https:\/\/www.youtube.com\/user\/PatternEnergy?app=desktop","https:\/\/web.cauze.com\/company\/293"]},{"@type":"Person","@id":"https:\/\/patternenergy.com\/es\/#\/schema\/person\/6f7080f7c9428a32a6bbe73bf6c8e412","name":"Alisa Frincke","url":"https:\/\/patternenergy.com\/es\/author\/alisa\/"}]}},"_links":{"self":[{"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/posts\/18591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/comments?post=18591"}],"version-history":[{"count":0,"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/posts\/18591\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/media\/16088"}],"wp:attachment":[{"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/media?parent=18591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/categories?post=18591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/tags?post=18591"},{"taxonomy":"sub_site","embeddable":true,"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/sub_site?post=18591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}