{"id":18090,"date":"2021-06-24T15:21:36","date_gmt":"2021-06-24T20:21:36","guid":{"rendered":"https:\/\/patternenergy.com\/respetar-la-naturaleza-salvaje\/"},"modified":"2026-02-19T03:58:19","modified_gmt":"2026-02-19T08:58:19","slug":"respetar-la-naturaleza-salvaje","status":"publish","type":"post","link":"https:\/\/patternenergy.com\/es\/respetar-la-naturaleza-salvaje\/","title":{"rendered":"Respetar la naturaleza salvaje"},"content":{"rendered":"&#13;\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"880\" height=\"678\" class=\"wp-image-3140\" src=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2021\/12\/3-10.jpg\" alt=\"\"\/>&#13;\n<figcaption><strong><em>\u00bfQu\u00e9 debe hacer si encuentra una cr\u00eda de animal salvaje?<\/em><\/strong><\/figcaption>&#13;\n<\/figure>&#13;\n&#13;\n<p>Puede parecer que esa cr\u00eda de p\u00e1jaro o conejo en el jard\u00edn ha sido abandonada por sus padres, pero lo m\u00e1s probable es que no sea as\u00ed.<\/p>&#13;\n&#13;\n<p>Cuando se trata de la vida salvaje, Chantal Theijn, del<a href=\"http:\/\/www.hobbitstee.com\/index.php\"> Refugio Hobbitstee<\/a> de Jarvis (Ontario), dice que es importante no antropomorfizar a los animales salvajes. Chantal fund\u00f3 el Refugio en 2007 con modestas ambiciones y desde entonces lo ha convertido en un importante recurso para la rehabilitaci\u00f3n, educaci\u00f3n, mitigaci\u00f3n e investigaci\u00f3n de la fauna salvaje.<\/p>&#13;\n&#13;\n<p>\u00abLa fauna salvaje es salvaje por definici\u00f3n, y no se puede medir con los mismos criterios con que medimos a nuestros perros y gatos\u00bb, afirma Chantal. \u00abEs peligroso antropomorfizar la fauna salvaje porque, a diferencia de perros y gatos, no est\u00e1 domesticada. Quiero que la gente sea consciente de la naturaleza salvaje de la fauna y de la necesidad de que sean salvajes\u00bb.<\/p>&#13;\n&#13;\n<figure class=\"wp-block-pullquote\">&#13;\n<blockquote>&#13;\n<p>\u00abLos animales, como los humanos, no se apresuran a abandonar a sus cr\u00edas\u00bb.<\/p>&#13;\n<\/blockquote>&#13;\n<\/figure>&#13;\n&#13;\n<p><strong>M\u00e1s mal que bien<\/strong><\/p>&#13;\n&#13;\n<p>Cuando alguien ve una cr\u00eda de animal sola, quiere salvarla y cuidarla, pero Chantal dice que eso puede ser perjudicial para el animal.<\/p>&#13;\n&#13;\n<p>\u00abSi las cr\u00edas no se alimentan y cr\u00edan adecuadamente, pueden arruinar el resto de sus vidas. Cosas como la enfermedad \u00f3sea metab\u00f3lica y la falta de ciertos nutrientes en su dieta causan muchos problemas, de forma muy parecida a como ocurrir\u00eda en un ser humano.\u00bb<\/p>&#13;\n&#13;\n<p>Dice que lo m\u00e1s probable es que el beb\u00e9 haya sido separado temporalmente de su madre, no abandonado.<\/p>&#13;\n&#13;\n<p>\u00abLos animales -como los humanos- no se apresuran a abandonar a sus cr\u00edas. Ahora es temporada de ciervos beb\u00e9. Los cervatillos tienen fama de que las madres los dejan solos durante largos periodos de tiempo, y es muy dif\u00edcil convencer a la gente de que deje a los cervatillos tranquilos. Por desgracia, muchas cr\u00edas de animales salvajes son retiradas por error porque la gente cree que han sido abandonadas.<\/p>&#13;\n&#13;\n<p>Chantal dice que es preferible reunir o acoger a una cr\u00eda y llevarla al centro de rescate de animales salvajes s\u00f3lo si est\u00e1 herida o enferma. Puede leer m\u00e1s sobre el proceso de reunificaci\u00f3n en su <a href=\"https:\/\/medium.com\/natural-world\/the-reason-why-you-should-not-feed-injured-orphaned-wildlife-54dede7e6926\">blog<\/a>.<\/p>&#13;\n&#13;\n<p><strong>La expansi\u00f3n est\u00e1 en el horizonte<\/strong><\/p>&#13;\n&#13;\n<p>Chantal y su equipo de voluntarios est\u00e1n siempre ocupados. M\u00e1s de 3.000 animales salvajes llegan al refugio cada a\u00f1o.<\/p>&#13;\n&#13;\n<p>\u00abNuestra funci\u00f3n principal es rehabilitar animales salvajes enfermos, heridos y hu\u00e9rfanos, sobre todo los que est\u00e1n en peligro por culpa de los humanos. Intentamos devolver a la naturaleza a todos los que podemos. Tambi\u00e9n trabajamos con otros organismos para ayudar a identificar y mitigar zonas muy problem\u00e1ticas, como tramos de carreteras donde las tortugas suelen ser atropelladas por veh\u00edculos.\u00bb<\/p>&#13;\n&#13;\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"880\" height=\"678\" class=\"wp-image-3136\" src=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2021\/12\/1-9.jpg\" alt=\"\"\/><\/figure>&#13;\n&#13;\n<p>Chantal dice que su equipo se est\u00e1 quedando sin espacio, pero est\u00e1n trabajando en un plan para ampliarlo.<\/p>&#13;\n&#13;\n<p>\u00abQueremos rehabilitar m\u00e1s animales, pero nuestro edificio no es lo bastante grande para acoger a m\u00e1s voluntarios. La ampliaci\u00f3n tambi\u00e9n nos permitir\u00eda tener recintos exteriores m\u00e1s grandes y mejores para los animales salvajes. Pero algo que siempre he querido es tener un laboratorio in situ. Las enfermedades de los animales salvajes suelen pasarse por alto y siempre tenemos problemas con los laboratorios existentes. Podr\u00eda servir para investigar y conocer mejor la prevalencia de ciertas enfermedades en la zona\u00bb.<\/p>&#13;\n&#13;\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"880\" height=\"678\" class=\"wp-image-3138\" src=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2021\/12\/2-9.jpg\" alt=\"\"\/><\/figure>&#13;\n&#13;\n<p>A medida que disminuyan las restricciones a las reuniones, Chantal espera reanudar los actos de recaudaci\u00f3n de fondos para que el equipo de Hobbitstee pueda seguir educando y concienciando sobre la importancia de mantener la vida silvestre en su h\u00e1bitat natural.\u00bfLe interesa saber m\u00e1s sobre el Refugio de Vida Silvestre Hobbitstee? Siga su p\u00e1gina en<a href=\"https:\/\/www.facebook.com\/Hobbitstee\"> Facebook<\/a> o<a href=\"http:\/\/www.hobbitstee.com\/newslettersignup.php\"> suscr\u00edbase a su bolet\u00edn de noticias<\/a> para estar informado. Tambi\u00e9n puede seguir el blog de Chantal <a href=\"https:\/\/medium.com\/natural-world\/the-reason-why-you-should-not-feed-injured-orphaned-wildlife-54dede7e6926\">haciendo clic aqu\u00ed<\/a>.<\/p>&#13;\n","protected":false},"excerpt":{"rendered":"<p>Puede parecer que esa cr\u00eda de p\u00e1jaro o conejo en el jard\u00edn ha sido abandonada por sus padres, pero lo m\u00e1s probable es que no sea as\u00ed.<\/p>\n","protected":false},"author":3,"featured_media":10438,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[513,637,447],"tags":[858,606,857,859],"sub_site":[],"class_list":["post-18090","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-canada-es","category-patron-canada-historias","category-sin-categorizar","tag-bebes-animales","tag-gran-renovable","tag-rescate-de-animales","tag-vida-salvaje"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Respetar la naturaleza salvaje - Pattern Energy<\/title>\n<meta name=\"description\" content=\"Puede ser dif\u00edcil alejarse de ellos, pero los beb\u00e9s no suelen ser abandonados por sus padres. \u00bfQu\u00e9 debe hacer si encuentra una cr\u00eda de conejo, mapache o p\u00e1jaro? Lea m\u00e1s para descubrirlo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/patternenergy.com\/es\/respetar-la-naturaleza-salvaje\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Respetar la naturaleza salvaje - Pattern Energy\" \/>\n<meta property=\"og:description\" content=\"Puede ser dif\u00edcil alejarse de ellos, pero los beb\u00e9s no suelen ser abandonados por sus padres. \u00bfQu\u00e9 debe hacer si encuentra una cr\u00eda de conejo, mapache o p\u00e1jaro? Lea m\u00e1s para descubrirlo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/patternenergy.com\/es\/respetar-la-naturaleza-salvaje\/\" \/>\n<meta property=\"og:site_name\" content=\"Pattern Energy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PatternEnergy\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-24T20:21:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-19T08:58:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2021\/06\/Pattern-CAN-Featured-Images.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"672\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alisa Frincke\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alisa Frincke\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/respetar-la-naturaleza-salvaje\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/respetar-la-naturaleza-salvaje\\\/\"},\"author\":{\"name\":\"Alisa Frincke\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/#\\\/schema\\\/person\\\/6f7080f7c9428a32a6bbe73bf6c8e412\"},\"headline\":\"Respetar la naturaleza salvaje\",\"datePublished\":\"2021-06-24T20:21:36+00:00\",\"dateModified\":\"2026-02-19T08:58:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/respetar-la-naturaleza-salvaje\\\/\"},\"wordCount\":673,\"publisher\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/respetar-la-naturaleza-salvaje\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/patternenergy.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Pattern-CAN-Featured-Images.jpg\",\"keywords\":[\"beb\u00e9s animales\",\"Gran Renovable\",\"rescate de animales\",\"Vida salvaje\"],\"articleSection\":[\"Canad\u00e1\",\"Patr\u00f3n Canad\u00e1 Historias\",\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/respetar-la-naturaleza-salvaje\\\/\",\"url\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/respetar-la-naturaleza-salvaje\\\/\",\"name\":\"Respetar la naturaleza salvaje - Pattern Energy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/respetar-la-naturaleza-salvaje\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/respetar-la-naturaleza-salvaje\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/patternenergy.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Pattern-CAN-Featured-Images.jpg\",\"datePublished\":\"2021-06-24T20:21:36+00:00\",\"dateModified\":\"2026-02-19T08:58:19+00:00\",\"description\":\"Puede ser dif\u00edcil alejarse de ellos, pero los beb\u00e9s no suelen ser abandonados por sus padres. \u00bfQu\u00e9 debe hacer si encuentra una cr\u00eda de conejo, mapache o p\u00e1jaro? Lea m\u00e1s para descubrirlo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/respetar-la-naturaleza-salvaje\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/patternenergy.com\\\/es\\\/respetar-la-naturaleza-salvaje\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/respetar-la-naturaleza-salvaje\\\/#primaryimage\",\"url\":\"https:\\\/\\\/patternenergy.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Pattern-CAN-Featured-Images.jpg\",\"contentUrl\":\"https:\\\/\\\/patternenergy.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Pattern-CAN-Featured-Images.jpg\",\"width\":1080,\"height\":672},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/respetar-la-naturaleza-salvaje\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Respetar la naturaleza salvaje\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/\",\"name\":\"Pattern Energy\",\"description\":\"Desarrollamos, construimos, poseemos y explotamos proyectos e\u00f3licos, solares, de transmisi\u00f3n y de almacenamiento de energ\u00eda de alta calidad en todo el mundo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/#organization\",\"name\":\"Pattern Energy\",\"url\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/patternenergy.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Pattern-Energy-Media-thumbnail-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/patternenergy.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Pattern-Energy-Media-thumbnail-logo.jpg\",\"width\":1200,\"height\":627,\"caption\":\"Pattern Energy\"},\"image\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PatternEnergy\\\/\",\"https:\\\/\\\/instagram.com\\\/patternenergy?utm_medium=copy_link\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pattern-energy\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/PatternEnergy?app=desktop\",\"https:\\\/\\\/web.cauze.com\\\/company\\\/293\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/#\\\/schema\\\/person\\\/6f7080f7c9428a32a6bbe73bf6c8e412\",\"name\":\"Alisa Frincke\",\"url\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/author\\\/alisa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Respetar la naturaleza salvaje - Pattern Energy","description":"Puede ser dif\u00edcil alejarse de ellos, pero los beb\u00e9s no suelen ser abandonados por sus padres. \u00bfQu\u00e9 debe hacer si encuentra una cr\u00eda de conejo, mapache o p\u00e1jaro? Lea m\u00e1s para descubrirlo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/patternenergy.com\/es\/respetar-la-naturaleza-salvaje\/","og_locale":"es_ES","og_type":"article","og_title":"Respetar la naturaleza salvaje - Pattern Energy","og_description":"Puede ser dif\u00edcil alejarse de ellos, pero los beb\u00e9s no suelen ser abandonados por sus padres. \u00bfQu\u00e9 debe hacer si encuentra una cr\u00eda de conejo, mapache o p\u00e1jaro? Lea m\u00e1s para descubrirlo.","og_url":"https:\/\/patternenergy.com\/es\/respetar-la-naturaleza-salvaje\/","og_site_name":"Pattern Energy","article_publisher":"https:\/\/www.facebook.com\/PatternEnergy\/","article_published_time":"2021-06-24T20:21:36+00:00","article_modified_time":"2026-02-19T08:58:19+00:00","og_image":[{"width":1080,"height":672,"url":"https:\/\/patternenergy.com\/wp-content\/uploads\/2021\/06\/Pattern-CAN-Featured-Images.jpg","type":"image\/jpeg"}],"author":"Alisa Frincke","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Alisa Frincke","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/patternenergy.com\/es\/respetar-la-naturaleza-salvaje\/#article","isPartOf":{"@id":"https:\/\/patternenergy.com\/es\/respetar-la-naturaleza-salvaje\/"},"author":{"name":"Alisa Frincke","@id":"https:\/\/patternenergy.com\/es\/#\/schema\/person\/6f7080f7c9428a32a6bbe73bf6c8e412"},"headline":"Respetar la naturaleza salvaje","datePublished":"2021-06-24T20:21:36+00:00","dateModified":"2026-02-19T08:58:19+00:00","mainEntityOfPage":{"@id":"https:\/\/patternenergy.com\/es\/respetar-la-naturaleza-salvaje\/"},"wordCount":673,"publisher":{"@id":"https:\/\/patternenergy.com\/es\/#organization"},"image":{"@id":"https:\/\/patternenergy.com\/es\/respetar-la-naturaleza-salvaje\/#primaryimage"},"thumbnailUrl":"https:\/\/patternenergy.com\/wp-content\/uploads\/2021\/06\/Pattern-CAN-Featured-Images.jpg","keywords":["beb\u00e9s animales","Gran Renovable","rescate de animales","Vida salvaje"],"articleSection":["Canad\u00e1","Patr\u00f3n Canad\u00e1 Historias","Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/patternenergy.com\/es\/respetar-la-naturaleza-salvaje\/","url":"https:\/\/patternenergy.com\/es\/respetar-la-naturaleza-salvaje\/","name":"Respetar la naturaleza salvaje - Pattern Energy","isPartOf":{"@id":"https:\/\/patternenergy.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/patternenergy.com\/es\/respetar-la-naturaleza-salvaje\/#primaryimage"},"image":{"@id":"https:\/\/patternenergy.com\/es\/respetar-la-naturaleza-salvaje\/#primaryimage"},"thumbnailUrl":"https:\/\/patternenergy.com\/wp-content\/uploads\/2021\/06\/Pattern-CAN-Featured-Images.jpg","datePublished":"2021-06-24T20:21:36+00:00","dateModified":"2026-02-19T08:58:19+00:00","description":"Puede ser dif\u00edcil alejarse de ellos, pero los beb\u00e9s no suelen ser abandonados por sus padres. \u00bfQu\u00e9 debe hacer si encuentra una cr\u00eda de conejo, mapache o p\u00e1jaro? Lea m\u00e1s para descubrirlo.","breadcrumb":{"@id":"https:\/\/patternenergy.com\/es\/respetar-la-naturaleza-salvaje\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/patternenergy.com\/es\/respetar-la-naturaleza-salvaje\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patternenergy.com\/es\/respetar-la-naturaleza-salvaje\/#primaryimage","url":"https:\/\/patternenergy.com\/wp-content\/uploads\/2021\/06\/Pattern-CAN-Featured-Images.jpg","contentUrl":"https:\/\/patternenergy.com\/wp-content\/uploads\/2021\/06\/Pattern-CAN-Featured-Images.jpg","width":1080,"height":672},{"@type":"BreadcrumbList","@id":"https:\/\/patternenergy.com\/es\/respetar-la-naturaleza-salvaje\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/patternenergy.com\/es\/"},{"@type":"ListItem","position":2,"name":"Respetar la naturaleza salvaje"}]},{"@type":"WebSite","@id":"https:\/\/patternenergy.com\/es\/#website","url":"https:\/\/patternenergy.com\/es\/","name":"Pattern Energy","description":"Desarrollamos, construimos, poseemos y explotamos proyectos e\u00f3licos, solares, de transmisi\u00f3n y de almacenamiento de energ\u00eda de alta calidad en todo el mundo.","publisher":{"@id":"https:\/\/patternenergy.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/patternenergy.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/patternenergy.com\/es\/#organization","name":"Pattern Energy","url":"https:\/\/patternenergy.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patternenergy.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/01\/Pattern-Energy-Media-thumbnail-logo.jpg","contentUrl":"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/01\/Pattern-Energy-Media-thumbnail-logo.jpg","width":1200,"height":627,"caption":"Pattern Energy"},"image":{"@id":"https:\/\/patternenergy.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PatternEnergy\/","https:\/\/instagram.com\/patternenergy?utm_medium=copy_link","https:\/\/www.linkedin.com\/company\/pattern-energy","https:\/\/www.youtube.com\/user\/PatternEnergy?app=desktop","https:\/\/web.cauze.com\/company\/293"]},{"@type":"Person","@id":"https:\/\/patternenergy.com\/es\/#\/schema\/person\/6f7080f7c9428a32a6bbe73bf6c8e412","name":"Alisa Frincke","url":"https:\/\/patternenergy.com\/es\/author\/alisa\/"}]}},"_links":{"self":[{"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/posts\/18090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/comments?post=18090"}],"version-history":[{"count":0,"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/posts\/18090\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/media\/10438"}],"wp:attachment":[{"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/media?parent=18090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/categories?post=18090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/tags?post=18090"},{"taxonomy":"sub_site","embeddable":true,"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/sub_site?post=18090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}