{"id":17570,"date":"2018-10-16T16:59:00","date_gmt":"2018-10-16T21:59:00","guid":{"rendered":"https:\/\/patternenergy.com\/danna-small-de-pattern-sera-ponente-en-la-proxima-canwea-sobre-gestion-de-los-impactos-en-los-murcielagos-de-los-parques-eolicos-canadienses\/"},"modified":"2026-06-03T12:50:43","modified_gmt":"2026-06-03T17:50:43","slug":"danna-small-de-pattern-sera-ponente-en-la-proxima-canwea-sobre-gestion-de-los-impactos-en-los-murcielagos-de-los-parques-eolicos-canadienses","status":"publish","type":"post","link":"https:\/\/patternenergy.com\/es\/danna-small-de-pattern-sera-ponente-en-la-proxima-canwea-sobre-gestion-de-los-impactos-en-los-murcielagos-de-los-parques-eolicos-canadienses\/","title":{"rendered":"Danna Small, de Pattern, ser\u00e1 ponente en la pr\u00f3xima CANWEA sobre \u00abGesti\u00f3n de los impactos en los murci\u00e9lagos de los parques e\u00f3licos canadienses\u00bb."},"content":{"rendered":"&#13;\n<p class=\"wp-block-paragraph\">Danna Small, Responsable de Medio Ambiente, har\u00e1 una presentaci\u00f3n el<sup>23 de<\/sup> octubre en el taller previo a la conferencia de CANWEA: Wind Energy and Bat Conservation Symposium &#8211; Managing Impacts to Bats at Canadian Wind Farms.  <\/p>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">Danna gestiona las responsabilidades de Operaciones Medioambientales de Pattern desde noviembre de 2016. En ese tiempo, Danna ha asumido un papel de liderazgo con CANWEA para completar el <strong><a href=\"https:\/\/canwea.ca\/wind-facts\/wildlife\/wind-energy-and-bat-conservation-review\/\">documento de revisi\u00f3n de la conservaci\u00f3n de los murci\u00e9lagos<\/a> <\/strong>y como representante del sector en el Comit\u00e9 Directivo de la Base de Datos de Seguimiento de Aves y Murci\u00e9lagos. Danna hablar\u00e1 de nuestras experiencias recientes en el MSM, donde la ciencia oportuna y de calidad result\u00f3 eficaz para convencer a la agencia de que aceptara un plan de mitigaci\u00f3n de murci\u00e9lagos m\u00e1s viable.  <\/p>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">  Brandy Giannetta, de CANWEA, es quien mejor lo resume: \u00ab<em>Por eso es importante que, como industria, seamos sensibles a nuestros posibles efectos y nos basemos en datos para evitarlos, minimizarlos y mitigarlos. La nueva revisi\u00f3n de murci\u00e9lagos de CanWEA proporciona a la industria, los reguladores, los responsables pol\u00edticos y otras partes interesadas un marco para trabajar en colaboraci\u00f3n con el fin de proteger a los murci\u00e9lagos, al tiempo que se apoya el desarrollo del tan necesario suministro de energ\u00eda limpia.\u00bb<\/em><\/p>&#13;\n","protected":false},"excerpt":{"rendered":"<p>&#13; Danna Small, Responsable de Medio Ambiente, har\u00e1 una presentaci\u00f3n el23 de octubre en el taller previo a la conferencia de CANWEA: Wind Energy and Bat Conservation Symposium &#8211; Managing Impacts to Bats at Canadian Wind Farms. &#13; &#13; Danna gestiona las responsabilidades de Operaciones Medioambientales de Pattern desde noviembre de 2016. En ese tiempo, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[513,527,528,447],"tags":[],"sub_site":[],"class_list":["post-17570","post","type-post","status-publish","format-standard","hentry","category-canada-es","category-noticias-de-pattern-energy","category-patrones","category-sin-categorizar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Danna Small, de Pattern, ser\u00e1 ponente en la pr\u00f3xima CANWEA sobre &quot;Gesti\u00f3n de los impactos en los murci\u00e9lagos de los parques e\u00f3licos canadienses&quot;. - Pattern Energy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/patternenergy.com\/es\/danna-small-de-pattern-sera-ponente-en-la-proxima-canwea-sobre-gestion-de-los-impactos-en-los-murcielagos-de-los-parques-eolicos-canadienses\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Danna Small, de Pattern, ser\u00e1 ponente en la pr\u00f3xima CANWEA sobre &quot;Gesti\u00f3n de los impactos en los murci\u00e9lagos de los parques e\u00f3licos canadienses&quot;. - Pattern Energy\" \/>\n<meta property=\"og:description\" content=\"&#013; Danna Small, Responsable de Medio Ambiente, har\u00e1 una presentaci\u00f3n el23 de octubre en el taller previo a la conferencia de CANWEA: Wind Energy and Bat Conservation Symposium &#8211; Managing Impacts to Bats at Canadian Wind Farms. &#013; &#013; Danna gestiona las responsabilidades de Operaciones Medioambientales de Pattern desde noviembre de 2016. En ese tiempo, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/patternenergy.com\/es\/danna-small-de-pattern-sera-ponente-en-la-proxima-canwea-sobre-gestion-de-los-impactos-en-los-murcielagos-de-los-parques-eolicos-canadienses\/\" \/>\n<meta property=\"og:site_name\" content=\"Pattern Energy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PatternEnergy\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-16T21:59:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-03T17:50:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/01\/Pattern-Energy-Media-thumbnail-logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ptrndmn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ptrndmn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/danna-small-de-pattern-sera-ponente-en-la-proxima-canwea-sobre-gestion-de-los-impactos-en-los-murcielagos-de-los-parques-eolicos-canadienses\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/danna-small-de-pattern-sera-ponente-en-la-proxima-canwea-sobre-gestion-de-los-impactos-en-los-murcielagos-de-los-parques-eolicos-canadienses\\\/\"},\"author\":{\"name\":\"ptrndmn\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/#\\\/schema\\\/person\\\/33965a118f27fded0be086c056aa2706\"},\"headline\":\"Danna Small, de Pattern, ser\u00e1 ponente en la pr\u00f3xima CANWEA sobre \u00abGesti\u00f3n de los impactos en los murci\u00e9lagos de los parques e\u00f3licos canadienses\u00bb.\",\"datePublished\":\"2018-10-16T21:59:00+00:00\",\"dateModified\":\"2026-06-03T17:50:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/danna-small-de-pattern-sera-ponente-en-la-proxima-canwea-sobre-gestion-de-los-impactos-en-los-murcielagos-de-los-parques-eolicos-canadienses\\\/\"},\"wordCount\":247,\"publisher\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/#organization\"},\"articleSection\":[\"Canad\u00e1\",\"Noticias de Pattern Energy\",\"Patrones\",\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/danna-small-de-pattern-sera-ponente-en-la-proxima-canwea-sobre-gestion-de-los-impactos-en-los-murcielagos-de-los-parques-eolicos-canadienses\\\/\",\"url\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/danna-small-de-pattern-sera-ponente-en-la-proxima-canwea-sobre-gestion-de-los-impactos-en-los-murcielagos-de-los-parques-eolicos-canadienses\\\/\",\"name\":\"Danna Small, de Pattern, ser\u00e1 ponente en la pr\u00f3xima CANWEA sobre \\\"Gesti\u00f3n de los impactos en los murci\u00e9lagos de los parques e\u00f3licos canadienses\\\". - Pattern Energy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/#website\"},\"datePublished\":\"2018-10-16T21:59:00+00:00\",\"dateModified\":\"2026-06-03T17:50:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/danna-small-de-pattern-sera-ponente-en-la-proxima-canwea-sobre-gestion-de-los-impactos-en-los-murcielagos-de-los-parques-eolicos-canadienses\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/patternenergy.com\\\/es\\\/danna-small-de-pattern-sera-ponente-en-la-proxima-canwea-sobre-gestion-de-los-impactos-en-los-murcielagos-de-los-parques-eolicos-canadienses\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/danna-small-de-pattern-sera-ponente-en-la-proxima-canwea-sobre-gestion-de-los-impactos-en-los-murcielagos-de-los-parques-eolicos-canadienses\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Danna Small, de Pattern, ser\u00e1 ponente en la pr\u00f3xima CANWEA sobre &#8220;Gesti\u00f3n de los impactos en los murci\u00e9lagos de los parques e\u00f3licos canadienses&#8221;.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/\",\"name\":\"Pattern Energy\",\"description\":\"Desarrollamos, construimos, poseemos y explotamos proyectos e\u00f3licos, solares, de transmisi\u00f3n y de almacenamiento de energ\u00eda de alta calidad en todo el mundo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/#organization\",\"name\":\"Pattern Energy\",\"url\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/patternenergy.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Pattern-Energy-Media-thumbnail-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/patternenergy.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Pattern-Energy-Media-thumbnail-logo.jpg\",\"width\":1200,\"height\":627,\"caption\":\"Pattern Energy\"},\"image\":{\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PatternEnergy\\\/\",\"https:\\\/\\\/instagram.com\\\/patternenergy?utm_medium=copy_link\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pattern-energy\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/PatternEnergy?app=desktop\",\"https:\\\/\\\/web.cauze.com\\\/company\\\/293\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/#\\\/schema\\\/person\\\/33965a118f27fded0be086c056aa2706\",\"name\":\"ptrndmn\",\"sameAs\":[\"https:\\\/\\\/patternenergy.com\"],\"url\":\"https:\\\/\\\/patternenergy.com\\\/es\\\/author\\\/ptrndmn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Danna Small, de Pattern, ser\u00e1 ponente en la pr\u00f3xima CANWEA sobre \"Gesti\u00f3n de los impactos en los murci\u00e9lagos de los parques e\u00f3licos canadienses\". - Pattern Energy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/patternenergy.com\/es\/danna-small-de-pattern-sera-ponente-en-la-proxima-canwea-sobre-gestion-de-los-impactos-en-los-murcielagos-de-los-parques-eolicos-canadienses\/","og_locale":"es_ES","og_type":"article","og_title":"Danna Small, de Pattern, ser\u00e1 ponente en la pr\u00f3xima CANWEA sobre \"Gesti\u00f3n de los impactos en los murci\u00e9lagos de los parques e\u00f3licos canadienses\". - Pattern Energy","og_description":"&#13; Danna Small, Responsable de Medio Ambiente, har\u00e1 una presentaci\u00f3n el23 de octubre en el taller previo a la conferencia de CANWEA: Wind Energy and Bat Conservation Symposium &#8211; Managing Impacts to Bats at Canadian Wind Farms. &#13; &#13; Danna gestiona las responsabilidades de Operaciones Medioambientales de Pattern desde noviembre de 2016. En ese tiempo, [&hellip;]","og_url":"https:\/\/patternenergy.com\/es\/danna-small-de-pattern-sera-ponente-en-la-proxima-canwea-sobre-gestion-de-los-impactos-en-los-murcielagos-de-los-parques-eolicos-canadienses\/","og_site_name":"Pattern Energy","article_publisher":"https:\/\/www.facebook.com\/PatternEnergy\/","article_published_time":"2018-10-16T21:59:00+00:00","article_modified_time":"2026-06-03T17:50:43+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/01\/Pattern-Energy-Media-thumbnail-logo.jpg","type":"image\/jpeg"}],"author":"ptrndmn","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ptrndmn","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/patternenergy.com\/es\/danna-small-de-pattern-sera-ponente-en-la-proxima-canwea-sobre-gestion-de-los-impactos-en-los-murcielagos-de-los-parques-eolicos-canadienses\/#article","isPartOf":{"@id":"https:\/\/patternenergy.com\/es\/danna-small-de-pattern-sera-ponente-en-la-proxima-canwea-sobre-gestion-de-los-impactos-en-los-murcielagos-de-los-parques-eolicos-canadienses\/"},"author":{"name":"ptrndmn","@id":"https:\/\/patternenergy.com\/es\/#\/schema\/person\/33965a118f27fded0be086c056aa2706"},"headline":"Danna Small, de Pattern, ser\u00e1 ponente en la pr\u00f3xima CANWEA sobre \u00abGesti\u00f3n de los impactos en los murci\u00e9lagos de los parques e\u00f3licos canadienses\u00bb.","datePublished":"2018-10-16T21:59:00+00:00","dateModified":"2026-06-03T17:50:43+00:00","mainEntityOfPage":{"@id":"https:\/\/patternenergy.com\/es\/danna-small-de-pattern-sera-ponente-en-la-proxima-canwea-sobre-gestion-de-los-impactos-en-los-murcielagos-de-los-parques-eolicos-canadienses\/"},"wordCount":247,"publisher":{"@id":"https:\/\/patternenergy.com\/es\/#organization"},"articleSection":["Canad\u00e1","Noticias de Pattern Energy","Patrones","Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/patternenergy.com\/es\/danna-small-de-pattern-sera-ponente-en-la-proxima-canwea-sobre-gestion-de-los-impactos-en-los-murcielagos-de-los-parques-eolicos-canadienses\/","url":"https:\/\/patternenergy.com\/es\/danna-small-de-pattern-sera-ponente-en-la-proxima-canwea-sobre-gestion-de-los-impactos-en-los-murcielagos-de-los-parques-eolicos-canadienses\/","name":"Danna Small, de Pattern, ser\u00e1 ponente en la pr\u00f3xima CANWEA sobre \"Gesti\u00f3n de los impactos en los murci\u00e9lagos de los parques e\u00f3licos canadienses\". - Pattern Energy","isPartOf":{"@id":"https:\/\/patternenergy.com\/es\/#website"},"datePublished":"2018-10-16T21:59:00+00:00","dateModified":"2026-06-03T17:50:43+00:00","breadcrumb":{"@id":"https:\/\/patternenergy.com\/es\/danna-small-de-pattern-sera-ponente-en-la-proxima-canwea-sobre-gestion-de-los-impactos-en-los-murcielagos-de-los-parques-eolicos-canadienses\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/patternenergy.com\/es\/danna-small-de-pattern-sera-ponente-en-la-proxima-canwea-sobre-gestion-de-los-impactos-en-los-murcielagos-de-los-parques-eolicos-canadienses\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/patternenergy.com\/es\/danna-small-de-pattern-sera-ponente-en-la-proxima-canwea-sobre-gestion-de-los-impactos-en-los-murcielagos-de-los-parques-eolicos-canadienses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/patternenergy.com\/es\/"},{"@type":"ListItem","position":2,"name":"Danna Small, de Pattern, ser\u00e1 ponente en la pr\u00f3xima CANWEA sobre &#8220;Gesti\u00f3n de los impactos en los murci\u00e9lagos de los parques e\u00f3licos canadienses&#8221;."}]},{"@type":"WebSite","@id":"https:\/\/patternenergy.com\/es\/#website","url":"https:\/\/patternenergy.com\/es\/","name":"Pattern Energy","description":"Desarrollamos, construimos, poseemos y explotamos proyectos e\u00f3licos, solares, de transmisi\u00f3n y de almacenamiento de energ\u00eda de alta calidad en todo el mundo.","publisher":{"@id":"https:\/\/patternenergy.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/patternenergy.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/patternenergy.com\/es\/#organization","name":"Pattern Energy","url":"https:\/\/patternenergy.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patternenergy.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/01\/Pattern-Energy-Media-thumbnail-logo.jpg","contentUrl":"https:\/\/patternenergy.com\/wp-content\/uploads\/2022\/01\/Pattern-Energy-Media-thumbnail-logo.jpg","width":1200,"height":627,"caption":"Pattern Energy"},"image":{"@id":"https:\/\/patternenergy.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PatternEnergy\/","https:\/\/instagram.com\/patternenergy?utm_medium=copy_link","https:\/\/www.linkedin.com\/company\/pattern-energy","https:\/\/www.youtube.com\/user\/PatternEnergy?app=desktop","https:\/\/web.cauze.com\/company\/293"]},{"@type":"Person","@id":"https:\/\/patternenergy.com\/es\/#\/schema\/person\/33965a118f27fded0be086c056aa2706","name":"ptrndmn","sameAs":["https:\/\/patternenergy.com"],"url":"https:\/\/patternenergy.com\/es\/author\/ptrndmn\/"}]}},"_links":{"self":[{"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/posts\/17570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/comments?post=17570"}],"version-history":[{"count":1,"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/posts\/17570\/revisions"}],"predecessor-version":[{"id":26071,"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/posts\/17570\/revisions\/26071"}],"wp:attachment":[{"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/media?parent=17570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/categories?post=17570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/tags?post=17570"},{"taxonomy":"sub_site","embeddable":true,"href":"https:\/\/patternenergy.com\/es\/wp-json\/wp\/v2\/sub_site?post=17570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}